{"id":9973,"date":"2023-03-01T13:31:00","date_gmt":"2023-03-01T12:31:00","guid":{"rendered":"https:\/\/apnu.be\/?p=9973"},"modified":"2025-11-11T10:16:18","modified_gmt":"2025-11-11T09:16:18","slug":"journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier","status":"publish","type":"post","link":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\/","title":{"rendered":"Journ\u00e9e internationale d\u00e9di\u00e9e \u00e0 la m\u00e9moire des victimes de l\u2019Holocauste &#8211; 27 janvier"},"content":{"rendered":"\n<p class=\"has-text-align-justify has-black-color has-text-color wp-block-paragraph\">Chaque ann\u00e9e, le 27 janvier, l\u2019Assembl\u00e9e g\u00e9n\u00e9rale des Nations Unies appelle \u00e0 comm\u00e9morer la <strong>m\u00e9moire des victimes de l\u2019Holocauste<\/strong>. Depuis 2005, elle a en effet fait de cette date, anniversaire de la lib\u00e9ration du camp de concentration et d\u2019extermination d\u2019Auschwitz-Birkenau, la \u201cJourn\u00e9e internationale d\u00e9di\u00e9e \u00e0 la m\u00e9moire des victimes de l\u2019Holocauste\u201d. En 2022, elle a par ailleurs adopt\u00e9 une r\u00e9solution condamnant toute remise en question de l\u2019historicit\u00e9 de la Shoah. Les Nations Unies organisent plusieurs \u00e9v\u00e9nements dans le cadre de ces comm\u00e9morations; la th\u00e9matique \u201cfoyer et appartenance\u201d a \u00e9t\u00e9 retenue pour celles de cette ann\u00e9e et permet d\u2019aborder les \u00e9victions, la fuite, les ghettos, la recherche d\u2019asile et les r\u00e9fugi\u00e9s avant, pendant et apr\u00e8s la deuxi\u00e8me guerre mondiale. Le Mus\u00e9e Caserne Dossin de Malines a pr\u00e9sent\u00e9 une exposition \u00e0 New York consacr\u00e9e aux effets d\u00e9l\u00e9t\u00e8res des st\u00e9r\u00e9otypes.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color wp-block-paragraph\">L\u2019Holocauste a laiss\u00e9 une trace profonde sur notre soci\u00e9t\u00e9. Alors que les survivants disparaissent \u00e0 leur tour, les lieux de m\u00e9moire jouent un r\u00f4le important pour rappeler les atrocit\u00e9s nazies et mettre en garde contre les id\u00e9ologies de haine, les violences n\u00e9es du racisme et&nbsp; de l\u2019antis\u00e9mitisme, les discriminations et les pr\u00e9jug\u00e9s pour en tirer des le\u00e7ons pour l\u2019avenir.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color wp-block-paragraph\">L\u2019UNESCO pour sa part <a href=\"https:\/\/www.unesco.org\/fr\/days\/holocaust-remembrance\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">r\u00e9affirme<\/mark><\/a> \u00ab\u202fson engagement ind\u00e9fectible \u00e0 lutter contre l\u2019antis\u00e9mitisme, le racisme et toutes les formes d\u2019intol\u00e9rance qui peuvent conduire \u00e0 la violence cibl\u00e9e sur un groupe\u202f\u00bb. Son action est notamment tourn\u00e9e vers l\u2019\u00e9ducation des jeunes g\u00e9n\u00e9rations, au temps de l\u2019\u00e8re num\u00e9rique o\u00f9 les discours de haine s\u2019intensifient trop ais\u00e9ment. Un <a href=\"https:\/\/news.un.org\/fr\/story\/2022\/01\/1113052\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">partenariat<\/mark><\/a> a \u00e9t\u00e9 conclu entre l\u2019UNESCO et le Congr\u00e8s juif mondial avec Facebook et Tiktok \u00ab\u202fvisant \u00e0 garantir que les recherches sur l\u2019Holocauste effectu\u00e9es sur ces plateformes redirigent les utilisateurs vers des informations v\u00e9rifi\u00e9es\u202f\u00bb.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color wp-block-paragraph\">On c\u00e9l\u00e8bre \u00e9galement cette ann\u00e9e le<strong> 75e anniversaire de la D\u00e9claration universelle des droits de l\u2019Homme<\/strong>, con\u00e7ue et adopt\u00e9e en r\u00e9action directe aux horreurs de la deuxi\u00e8me guerre mondiale. Dans sa <a href=\"https:\/\/www.ohchr.org\/fr\/statements-and-speeches\/2023\/01\/holocaust-remembrance-day-statement-high-commissioner\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">d\u00e9claration du 26 janvier 2023<\/mark><\/a>, Volker T\u00fcrk, le Haut-Commissaire des Nations Unies aux droits de l\u2019Homme, a rappel\u00e9 qu\u2019il s\u2019agit d\u2019un \u00ab\u202fengagement pris par les dirigeants du monde entier montrant que la justice, le respect de la dignit\u00e9 humaine, l\u2019\u00e9galit\u00e9 et les droits sont essentiels \u00e0 une paix durable\u202f\u00bb.\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">R\u00e9dig\u00e9 par Janaert Coraline, \u00e9tudiante en 2e ann\u00e9e de Master en droit, \u00e0 finalit\u00e9 droit europ\u00e9en \u00e0 l\u2019UCLouvain.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les Nations Unies organisent plusieurs \u00e9v\u00e9nements dans le cadre de ces comm\u00e9morations; la th\u00e9matique \u201cfoyer et appartenance\u201d a \u00e9t\u00e9 retenue pour celles de cette ann\u00e9e <\/p>\n","protected":false},"author":1,"featured_media":9974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[118],"tags":[176],"class_list":["post-9973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles","tag-holocauste"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Journ\u00e9e internationale d\u00e9di\u00e9e \u00e0 la m\u00e9moire des victimes de l\u2019Holocauste - 27 janvier - APNU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apnu.be\/index.php\/2023\/03\/01\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Journ\u00e9e internationale d\u00e9di\u00e9e \u00e0 la m\u00e9moire des victimes de l\u2019Holocauste - 27 janvier - APNU\" \/>\n<meta property=\"og:description\" content=\"Les Nations Unies organisent plusieurs \u00e9v\u00e9nements dans le cadre de ces comm\u00e9morations; la th\u00e9matique \u201cfoyer et appartenance\u201d a \u00e9t\u00e9 retenue pour celles de cette ann\u00e9e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apnu.be\/index.php\/2023\/03\/01\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\/\" \/>\n<meta property=\"og:site_name\" content=\"APNU\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-01T12:31:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-11T09:16:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apnu.be\/wp-content\/uploads\/2023\/03\/Photo-ONU-Photo-Mark-Garten-6-1024x577.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"577\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\"},\"headline\":\"Journ\u00e9e internationale d\u00e9di\u00e9e \u00e0 la m\u00e9moire des victimes de l\u2019Holocauste &#8211; 27 janvier\",\"datePublished\":\"2023-03-01T12:31:00+00:00\",\"dateModified\":\"2025-11-11T09:16:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\\\/\"},\"wordCount\":477,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Photo-ONU-Photo-Mark-Garten-6.png\",\"keywords\":[\"Holocauste\"],\"articleSection\":[\"Articles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\\\/\",\"url\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\\\/\",\"name\":\"Journ\u00e9e internationale d\u00e9di\u00e9e \u00e0 la m\u00e9moire des victimes de l\u2019Holocauste - 27 janvier - APNU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Photo-ONU-Photo-Mark-Garten-6.png\",\"datePublished\":\"2023-03-01T12:31:00+00:00\",\"dateModified\":\"2025-11-11T09:16:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\\\/#primaryimage\",\"url\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Photo-ONU-Photo-Mark-Garten-6.png\",\"contentUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Photo-ONU-Photo-Mark-Garten-6.png\",\"width\":1640,\"height\":924},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/apnu.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journ\u00e9e internationale d\u00e9di\u00e9e \u00e0 la m\u00e9moire des victimes de l\u2019Holocauste &#8211; 27 janvier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#website\",\"url\":\"https:\\\/\\\/apnu.be\\\/\",\"name\":\"APNU\",\"description\":\"L\u2019Association pour les Nations Unies (A.P.N.U.). Association sans but lucratif (A.S.B.L.)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apnu.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Journ\u00e9e internationale d\u00e9di\u00e9e \u00e0 la m\u00e9moire des victimes de l\u2019Holocauste - 27 janvier - APNU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\/","og_locale":"fr_FR","og_type":"article","og_title":"Journ\u00e9e internationale d\u00e9di\u00e9e \u00e0 la m\u00e9moire des victimes de l\u2019Holocauste - 27 janvier - APNU","og_description":"Les Nations Unies organisent plusieurs \u00e9v\u00e9nements dans le cadre de ces comm\u00e9morations; la th\u00e9matique \u201cfoyer et appartenance\u201d a \u00e9t\u00e9 retenue pour celles de cette ann\u00e9e","og_url":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\/","og_site_name":"APNU","article_published_time":"2023-03-01T12:31:00+00:00","article_modified_time":"2025-11-11T09:16:18+00:00","og_image":[{"width":1024,"height":577,"url":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/03\/Photo-ONU-Photo-Mark-Garten-6-1024x577.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\/#article","isPartOf":{"@id":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\/"},"author":{"name":"admin","@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc"},"headline":"Journ\u00e9e internationale d\u00e9di\u00e9e \u00e0 la m\u00e9moire des victimes de l\u2019Holocauste &#8211; 27 janvier","datePublished":"2023-03-01T12:31:00+00:00","dateModified":"2025-11-11T09:16:18+00:00","mainEntityOfPage":{"@id":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\/"},"wordCount":477,"commentCount":0,"image":{"@id":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\/#primaryimage"},"thumbnailUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/03\/Photo-ONU-Photo-Mark-Garten-6.png","keywords":["Holocauste"],"articleSection":["Articles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/apnu.be\/index.php\/2023\/03\/01\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\/","url":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\/","name":"Journ\u00e9e internationale d\u00e9di\u00e9e \u00e0 la m\u00e9moire des victimes de l\u2019Holocauste - 27 janvier - APNU","isPartOf":{"@id":"https:\/\/apnu.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\/#primaryimage"},"image":{"@id":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\/#primaryimage"},"thumbnailUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/03\/Photo-ONU-Photo-Mark-Garten-6.png","datePublished":"2023-03-01T12:31:00+00:00","dateModified":"2025-11-11T09:16:18+00:00","author":{"@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc"},"breadcrumb":{"@id":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apnu.be\/index.php\/2023\/03\/01\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\/#primaryimage","url":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/03\/Photo-ONU-Photo-Mark-Garten-6.png","contentUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/03\/Photo-ONU-Photo-Mark-Garten-6.png","width":1640,"height":924},{"@type":"BreadcrumbList","@id":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/journee-internationale-dediee-a-la-memoire-des-victimes-de-lholocauste-27-janvier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/apnu.be\/"},{"@type":"ListItem","position":2,"name":"Journ\u00e9e internationale d\u00e9di\u00e9e \u00e0 la m\u00e9moire des victimes de l\u2019Holocauste &#8211; 27 janvier"}]},{"@type":"WebSite","@id":"https:\/\/apnu.be\/#website","url":"https:\/\/apnu.be\/","name":"APNU","description":"L\u2019Association pour les Nations Unies (A.P.N.U.). Association sans but lucratif (A.S.B.L.)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apnu.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/apnu.be\/index.php\/author\/admin\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/03\/Photo-ONU-Photo-Mark-Garten-6.png","_links":{"self":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/9973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/comments?post=9973"}],"version-history":[{"count":3,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/9973\/revisions"}],"predecessor-version":[{"id":9977,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/9973\/revisions\/9977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/media\/9974"}],"wp:attachment":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/media?parent=9973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/categories?post=9973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/tags?post=9973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}