{"id":9954,"date":"2023-03-01T13:36:06","date_gmt":"2023-03-01T12:36:06","guid":{"rendered":"https:\/\/apnu.be\/?p=9954"},"modified":"2025-11-11T10:16:04","modified_gmt":"2025-11-11T09:16:04","slug":"israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023","status":"publish","type":"post","link":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\/","title":{"rendered":"Occupation des territoires palestiniens : la Cour Internationale de Justice et le Conseil de s\u00e9curit\u00e9 sollicit\u00e9s"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color wp-block-paragraph\"><strong>L\u2019Assembl\u00e9e g\u00e9n\u00e9rale de l\u2019ONU sollicite un avis consultatif de la Cour Internationale de justice sur l\u2019occupation isra\u00e9lienne des territoires palestiniens ; le Conseil de s\u00e9curit\u00e9 adopte une d\u00e9claration pr\u00e9sidentielle condamnant la l\u00e9galisation de colonies.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color wp-block-paragraph\">L&rsquo;Assembl\u00e9e g\u00e9n\u00e9rale des Nations Unies a adopt\u00e9, le 31 d\u00e9cembre 2022, une r\u00e9solution par laquelle elle sollicite un avis consultatif de la Cour Internationale de Justice (CIJ) sur l\u2019occupation isra\u00e9lienne des territoires palestiniens. Chaque ann\u00e9e, sur recommandation de sa 4e Commission, l\u2019Assembl\u00e9e g\u00e9n\u00e9rale adopte un \u201cpaquet\u201d de plusieurs r\u00e9solutions relatives respectivement \u00e0 l\u2019UNRWA, \u00e0 l\u2019occupation du Golan et aux pratiques isra\u00e9liennes dans les territoires palestiniens occup\u00e9s. La CIJ a d\u00e9j\u00e0 formul\u00e9 un avis consultatif sur l\u2019ill\u00e9galit\u00e9 du trac\u00e9 du mur de s\u00e9paration entre Isra\u00ebl et la Palestine, suite \u00e0 une demande de l\u2019AG, en 2004.<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color wp-block-paragraph\">La r\u00e9solution de l\u2019AG du 31 d\u00e9cembre sollicite un avis consultatif de la Cour sur les cons\u00e9quences juridiques de la violation par Isra\u00ebl du droit du peuple palestinien \u00e0 l\u2019auto-d\u00e9termination, r\u00e9sultant de l\u2019occupation prolong\u00e9e, des implantations et de l\u2019annexion de territoires palestiniens depuis 1967, y compris les mesures qui visent \u00e0 modifier la composition d\u00e9mographique, le caract\u00e8re et le statut de J\u00e9rusalem, ainsi que l\u2019adoption de l\u00e9gislations et mesures discriminatoires. Elle demande aussi que la Cour se prononce sur les effets que peuvent avoir ces pratiques sur le statut juridique de l\u2019occupation et les cons\u00e9quences juridiques que ceci peut entra\u00eener pour l\u2019ONU et les Etats membres. <\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color wp-block-paragraph\"><strong>En r\u00e9sum\u00e9, l\u2019occupation isra\u00e9lienne peut-elle encore \u00eatre qualifi\u00e9e d\u2019occupation au sens du droit international humanitaire ? <\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color wp-block-paragraph\">De tr\u00e8s nombreux Etats membres se sont abstenus ou n\u2019\u00e9taient pas pr\u00e9sents lors du vote de cette r\u00e9solution. 87 pays ont vot\u00e9 en faveur, y compris les pays arabes qui ont r\u00e9cemment normalis\u00e9 leurs relations avec Isra\u00ebl ; 27 ont vot\u00e9 contre, dont les Etats \u2013Unis, le Royaume Uni et le Canada ; 53 pays se sont abstenus. L\u2019Union europ\u00e9enne a vot\u00e9 en ordre dispers\u00e9 : l\u2019Autriche, la R\u00e9publique tch\u00e8que, la Croatie, l\u2019Estonie, l\u2019Allemagne, la Hongrie, l\u2019Italie, la Lituanie ont vot\u00e9 contre ; la Bulgarie, la Finlande, la France, Chypre, le Danemark, la Lettonie, les Pays-Bas, la Roumanie, la Slovaquie, l\u2019Espagne, et la Su\u00e8de se sont abstenus. Quant \u00e0 la Belgique, elle a vot\u00e9 en faveur de la r\u00e9solution, avec l\u2019Irlande, le Luxembourg, Malte, le Portugal, la Pologne, et la Slov\u00e9nie. Les opposants et des r\u00e9ticents ont justifi\u00e9 leur vote par l\u2019introduction tardive et non concert\u00e9e de cette demande d\u2019avis dans le texte de la r\u00e9solution, ou encore par le caract\u00e8re contreproductif d\u2019une telle d\u00e9marche dans la recherche d\u2019une solution n\u00e9goci\u00e9e au conflit isra\u00e9lo-palestinien.<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color wp-block-paragraph\">Le gouvernement isra\u00e9lien pour sa part annon\u00e7ait imm\u00e9diatement des mesures de r\u00e9torsion contre l\u2019Autorit\u00e9 palestinienne, accus\u00e9e de \u201cterrorisme diplomatico-juridique\u00a0\u00bb. En r\u00e9action, 70 pays, dont la Belgique, ont publi\u00e9 une d\u00e9claration confirmant leur soutien au r\u00f4le de la Cour Internationale de Justice et critiquant la r\u00e9action des autorit\u00e9s isra\u00e9liennes. Quelques jours plus tard, le Secr\u00e9taire g\u00e9n\u00e9ral lui-m\u00eame, dans un discours consacr\u00e9 \u00e0 l\u2019\u00e9tat de droit, a soulign\u00e9 l\u2019importance du r\u00f4le de la Cour dans le r\u00e8glement des conflits.<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color wp-block-paragraph\">Le 12 f\u00e9vrier, le gouvernement isra\u00e9lien approuvait la l\u00e9galisation de 9 implantations dans les territoires occup\u00e9s et l\u2019autorisation de construire 10.000 nouveaux logements dans les colonies. Les Emirats Arabes Unis, avec la d\u00e9l\u00e9gation palestinienne, s\u2019appr\u00eataient \u00e0 soumettre une r\u00e9solution au Conseil de s\u00e9curit\u00e9 en r\u00e9action \u00e0 cette nouvelle annonce. C\u2019est finalement une d\u00e9claration pr\u00e9sidentielle non contraignante qui a \u00e9t\u00e9 adopt\u00e9e par consensus au Conseil, le 20 f\u00e9vrier. Selon la presse isra\u00e9lienne, les Etats-Unis, qui souhaitaient \u00e9viter un vote, auraient discr\u00e8tement obtenu, en \u00e9change de cette concession, des engagements isra\u00e9liens \u00e0 ne pas mettre \u00e0 ex\u00e9cution la l\u00e9galisation annonc\u00e9e. Condamnant toutes les violences \u00e0 l\u2019\u00e9gard des civils et les actes de terrorisme, le Conseil de s\u00e9curit\u00e9 se d\u00e9clare constern\u00e9 par l\u2019annonce isra\u00e9lienne et rappelle combien le d\u00e9veloppement des implantations dans les territoires palestiniens occup\u00e9s met en danger la solution \u00e0 deux Etats.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>R\u00e9dig\u00e9 par B\u00e9n\u00e9dicte Frankinet &#8211; Administrateur APNU<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Assembl\u00e9e g\u00e9n\u00e9rale de l\u2019ONU sollicite un avis consultatif de la Cour Internationale de justice sur l\u2019occupation isra\u00e9lienne des territoires palestiniens ; le Conseil de s\u00e9curit\u00e9 adopte une d\u00e9claration pr\u00e9sidentielle condamnant la l\u00e9galisation de colonies.<\/p>\n","protected":false},"author":1,"featured_media":9955,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[118],"tags":[172,175,170,174,125],"class_list":["post-9954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles","tag-cij","tag-colonies","tag-israel","tag-occupation","tag-onu"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Occupation des territoires palestiniens : la Cour Internationale de Justice et le Conseil de s\u00e9curit\u00e9 sollicit\u00e9s - APNU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apnu.be\/index.php\/2023\/03\/01\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Occupation des territoires palestiniens : la Cour Internationale de Justice et le Conseil de s\u00e9curit\u00e9 sollicit\u00e9s - APNU\" \/>\n<meta property=\"og:description\" content=\"L\u2019Assembl\u00e9e g\u00e9n\u00e9rale de l\u2019ONU sollicite un avis consultatif de la Cour Internationale de justice sur l\u2019occupation isra\u00e9lienne des territoires palestiniens ; le Conseil de s\u00e9curit\u00e9 adopte une d\u00e9claration pr\u00e9sidentielle condamnant la l\u00e9galisation de colonies.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apnu.be\/index.php\/2023\/03\/01\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"APNU\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-01T12:36:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-11T09:16:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apnu.be\/wp-content\/uploads\/2023\/03\/Photo-ONU-Photo-Mark-Garten-3-e1677671255411.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"169\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\"},\"headline\":\"Occupation des territoires palestiniens : la Cour Internationale de Justice et le Conseil de s\u00e9curit\u00e9 sollicit\u00e9s\",\"datePublished\":\"2023-03-01T12:36:06+00:00\",\"dateModified\":\"2025-11-11T09:16:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\\\/\"},\"wordCount\":779,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Photo-ONU-Photo-Mark-Garten-3-e1677671255411.png\",\"keywords\":[\"CIJ\",\"colonies\",\"Israel\",\"occupation\",\"ONU\"],\"articleSection\":[\"Articles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\\\/\",\"url\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\\\/\",\"name\":\"Occupation des territoires palestiniens : la Cour Internationale de Justice et le Conseil de s\u00e9curit\u00e9 sollicit\u00e9s - APNU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Photo-ONU-Photo-Mark-Garten-3-e1677671255411.png\",\"datePublished\":\"2023-03-01T12:36:06+00:00\",\"dateModified\":\"2025-11-11T09:16:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Photo-ONU-Photo-Mark-Garten-3-e1677671255411.png\",\"contentUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Photo-ONU-Photo-Mark-Garten-3-e1677671255411.png\",\"width\":300,\"height\":169},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/03\\\/01\\\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/apnu.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Occupation des territoires palestiniens : la Cour Internationale de Justice et le Conseil de s\u00e9curit\u00e9 sollicit\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#website\",\"url\":\"https:\\\/\\\/apnu.be\\\/\",\"name\":\"APNU\",\"description\":\"L\u2019Association pour les Nations Unies (A.P.N.U.). Association sans but lucratif (A.S.B.L.)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apnu.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Occupation des territoires palestiniens : la Cour Internationale de Justice et le Conseil de s\u00e9curit\u00e9 sollicit\u00e9s - APNU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\/","og_locale":"fr_FR","og_type":"article","og_title":"Occupation des territoires palestiniens : la Cour Internationale de Justice et le Conseil de s\u00e9curit\u00e9 sollicit\u00e9s - APNU","og_description":"L\u2019Assembl\u00e9e g\u00e9n\u00e9rale de l\u2019ONU sollicite un avis consultatif de la Cour Internationale de justice sur l\u2019occupation isra\u00e9lienne des territoires palestiniens ; le Conseil de s\u00e9curit\u00e9 adopte une d\u00e9claration pr\u00e9sidentielle condamnant la l\u00e9galisation de colonies.","og_url":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\/","og_site_name":"APNU","article_published_time":"2023-03-01T12:36:06+00:00","article_modified_time":"2025-11-11T09:16:04+00:00","og_image":[{"width":300,"height":169,"url":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/03\/Photo-ONU-Photo-Mark-Garten-3-e1677671255411.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\/#article","isPartOf":{"@id":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\/"},"author":{"name":"admin","@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc"},"headline":"Occupation des territoires palestiniens : la Cour Internationale de Justice et le Conseil de s\u00e9curit\u00e9 sollicit\u00e9s","datePublished":"2023-03-01T12:36:06+00:00","dateModified":"2025-11-11T09:16:04+00:00","mainEntityOfPage":{"@id":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\/"},"wordCount":779,"commentCount":0,"image":{"@id":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/03\/Photo-ONU-Photo-Mark-Garten-3-e1677671255411.png","keywords":["CIJ","colonies","Israel","occupation","ONU"],"articleSection":["Articles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/apnu.be\/index.php\/2023\/03\/01\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\/","url":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\/","name":"Occupation des territoires palestiniens : la Cour Internationale de Justice et le Conseil de s\u00e9curit\u00e9 sollicit\u00e9s - APNU","isPartOf":{"@id":"https:\/\/apnu.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\/#primaryimage"},"image":{"@id":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/03\/Photo-ONU-Photo-Mark-Garten-3-e1677671255411.png","datePublished":"2023-03-01T12:36:06+00:00","dateModified":"2025-11-11T09:16:04+00:00","author":{"@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc"},"breadcrumb":{"@id":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apnu.be\/index.php\/2023\/03\/01\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\/#primaryimage","url":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/03\/Photo-ONU-Photo-Mark-Garten-3-e1677671255411.png","contentUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/03\/Photo-ONU-Photo-Mark-Garten-3-e1677671255411.png","width":300,"height":169},{"@type":"BreadcrumbList","@id":"https:\/\/apnu.be\/index.php\/2023\/03\/01\/israel-palestine-loccupation-israelienne-des-territoires-palestiniens-en-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/apnu.be\/"},{"@type":"ListItem","position":2,"name":"Occupation des territoires palestiniens : la Cour Internationale de Justice et le Conseil de s\u00e9curit\u00e9 sollicit\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/apnu.be\/#website","url":"https:\/\/apnu.be\/","name":"APNU","description":"L\u2019Association pour les Nations Unies (A.P.N.U.). Association sans but lucratif (A.S.B.L.)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apnu.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/apnu.be\/index.php\/author\/admin\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/03\/Photo-ONU-Photo-Mark-Garten-3-e1677671255411.png","_links":{"self":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/9954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/comments?post=9954"}],"version-history":[{"count":5,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/9954\/revisions"}],"predecessor-version":[{"id":9986,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/9954\/revisions\/9986"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/media\/9955"}],"wp:attachment":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/media?parent=9954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/categories?post=9954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/tags?post=9954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}