{"id":8952,"date":"2020-10-21T18:46:05","date_gmt":"2020-10-21T16:46:05","guid":{"rendered":"https:\/\/apnu.be\/?p=8952"},"modified":"2021-09-19T18:12:35","modified_gmt":"2021-09-19T16:12:35","slug":"24-octobre-les-nations-unies-ont-75-ans","status":"publish","type":"post","link":"https:\/\/apnu.be\/index.php\/2020\/10\/21\/24-octobre-les-nations-unies-ont-75-ans\/","title":{"rendered":"24 octobre 2020: les Nations Unies ont eu 75 ans"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Pour marquer le 75\u00e8me anniversaire de l&rsquo;entr\u00e9e en vigueur de la Charte des Nations Unies, vous trouverez ci-dessous des courtes vid\u00e9os reprenant les messages d&rsquo;Antonio Guterres, Secr\u00e9taire G\u00e9n\u00e9ral des Nations Unies et de quatre \u00e9minentes personnalit\u00e9s belges qui ont bien voulu les enregistrer pour l&rsquo;APNU. Nous les en remercions vivement.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"75\u00e8me anniversaire de la Charte des Nations Unies - Message du Secr\u00e9taire g\u00e9n\u00e9ral\" width=\"780\" height=\"439\" src=\"https:\/\/www.youtube.com\/embed\/wRPFgdPNY6A?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><figcaption><strong>&nbsp;Message du Secr\u00e9taire g\u00e9n\u00e9ral<\/strong><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Serge Brammertz, <\/strong>Procureur depuis 2016 du M\u00e9canisme international appel\u00e9 \u00e0 exercer les fonctions r\u00e9siduelles des Tribunaux p\u00e9naux internationaux, engag\u00e9 au plus haut niveau depuis le d\u00e9but des ann\u00e9es 2000 dans les m\u00e9canismes judiciaires internationaux , comme la Cour p\u00e9nale internationale et le Tribunal p\u00e9nal international pour l&rsquo;ex-Yougoslavie. Membre d&rsquo;honneur de l&rsquo;APNU:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"UN75 : Serge Brammetz\" width=\"780\" height=\"439\" src=\"https:\/\/www.youtube.com\/embed\/7_pitWEBTBw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Olivier De Schutter, <\/strong>professeur \u00e0 l&rsquo;UCLouvain, Rapporteur sp\u00e9cial des Nations Unies sur l\u2019extr\u00eame pauvret\u00e9 et les droits de l&rsquo;Homme, tr\u00e8s impliqu\u00e9 depuis plusieurs ann\u00e9es dans les institutions des Nations Unies traitant des droits \u00e9conomiques, sociaux et culturels, Pr\u00e9sident honoraire de l&rsquo;APNU:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"UN75 : Olivier De Schutter\" width=\"780\" height=\"585\" src=\"https:\/\/www.youtube.com\/embed\/9igr26MqPY0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jean-Pascal van Ypersele de Strihou, <\/strong>professeur \u00e0 l&rsquo;UCLouvain, membre depuis 1995 du Groupe intergouvernemental d&rsquo;experts sur l&rsquo;\u00e9volution du climat , dont il a \u00e9t\u00e9 le Vice-pr\u00e9sident de 2008 \u00e0 2015. Membre d&rsquo;honneur de l&rsquo;APNU:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"UN75 : Jean-Pascal van Ypersele\" width=\"780\" height=\"439\" src=\"https:\/\/www.youtube.com\/embed\/8T_WIvUvk5c?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pierre Galand<\/strong>, ancien S\u00e9nateur, Ma\u00eetre de conf\u00e9rence \u00e0 l&rsquo;ULB, tr\u00e8s impliqu\u00e9 dans le monde associatif comme fondateur ou pr\u00e9sident  de plusieurs associations de d\u00e9fense des droits des peuples et des droits de l&rsquo;Homme, Pr\u00e9sident honoraire de l&rsquo;APNU:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"UN75 : Pierre Galand\" width=\"780\" height=\"439\" src=\"https:\/\/www.youtube.com\/embed\/FI7MvMhBZlo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Pour marquer le 75\u00e8me anniversaire de l&rsquo;entr\u00e9e en vigueur de la Charte des Nations Unies,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":8958,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[109],"tags":[],"class_list":["post-8952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-ne-pas-manquer"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>24 octobre 2020: les Nations Unies ont eu 75 ans - APNU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apnu.be\/index.php\/2020\/10\/21\/24-octobre-les-nations-unies-ont-75-ans\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"24 octobre 2020: les Nations Unies ont eu 75 ans - APNU\" \/>\n<meta property=\"og:description\" content=\"Pour marquer le 75\u00e8me anniversaire de l&rsquo;entr\u00e9e en vigueur de la Charte des Nations Unies,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apnu.be\/index.php\/2020\/10\/21\/24-octobre-les-nations-unies-ont-75-ans\/\" \/>\n<meta property=\"og:site_name\" content=\"APNU\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-21T16:46:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-19T16:12:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apnu.be\/wp-content\/uploads\/2020\/10\/un75_fr-e1603563920448.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"864\" \/>\n\t<meta property=\"og:image:height\" content=\"417\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/10\\\/21\\\/24-octobre-les-nations-unies-ont-75-ans\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/10\\\/21\\\/24-octobre-les-nations-unies-ont-75-ans\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\"},\"headline\":\"24 octobre 2020: les Nations Unies ont eu 75 ans\",\"datePublished\":\"2020-10-21T16:46:05+00:00\",\"dateModified\":\"2021-09-19T16:12:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/10\\\/21\\\/24-octobre-les-nations-unies-ont-75-ans\\\/\"},\"wordCount\":292,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/10\\\/21\\\/24-octobre-les-nations-unies-ont-75-ans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/un75_fr-e1603563920448.jpg\",\"articleSection\":[\"\u00c0 ne pas manquer\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/10\\\/21\\\/24-octobre-les-nations-unies-ont-75-ans\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/10\\\/21\\\/24-octobre-les-nations-unies-ont-75-ans\\\/\",\"url\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/10\\\/21\\\/24-octobre-les-nations-unies-ont-75-ans\\\/\",\"name\":\"24 octobre 2020: les Nations Unies ont eu 75 ans - APNU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/10\\\/21\\\/24-octobre-les-nations-unies-ont-75-ans\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/10\\\/21\\\/24-octobre-les-nations-unies-ont-75-ans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/un75_fr-e1603563920448.jpg\",\"datePublished\":\"2020-10-21T16:46:05+00:00\",\"dateModified\":\"2021-09-19T16:12:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/10\\\/21\\\/24-octobre-les-nations-unies-ont-75-ans\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/10\\\/21\\\/24-octobre-les-nations-unies-ont-75-ans\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/10\\\/21\\\/24-octobre-les-nations-unies-ont-75-ans\\\/#primaryimage\",\"url\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/un75_fr-e1603563920448.jpg\",\"contentUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/un75_fr-e1603563920448.jpg\",\"width\":864,\"height\":417},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/10\\\/21\\\/24-octobre-les-nations-unies-ont-75-ans\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/apnu.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"24 octobre 2020: les Nations Unies ont eu 75 ans\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#website\",\"url\":\"https:\\\/\\\/apnu.be\\\/\",\"name\":\"APNU\",\"description\":\"L\u2019Association pour les Nations Unies (A.P.N.U.). Association sans but lucratif (A.S.B.L.)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apnu.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"24 octobre 2020: les Nations Unies ont eu 75 ans - APNU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apnu.be\/index.php\/2020\/10\/21\/24-octobre-les-nations-unies-ont-75-ans\/","og_locale":"fr_FR","og_type":"article","og_title":"24 octobre 2020: les Nations Unies ont eu 75 ans - APNU","og_description":"Pour marquer le 75\u00e8me anniversaire de l&rsquo;entr\u00e9e en vigueur de la Charte des Nations Unies,...","og_url":"https:\/\/apnu.be\/index.php\/2020\/10\/21\/24-octobre-les-nations-unies-ont-75-ans\/","og_site_name":"APNU","article_published_time":"2020-10-21T16:46:05+00:00","article_modified_time":"2021-09-19T16:12:35+00:00","og_image":[{"width":864,"height":417,"url":"https:\/\/apnu.be\/wp-content\/uploads\/2020\/10\/un75_fr-e1603563920448.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/apnu.be\/index.php\/2020\/10\/21\/24-octobre-les-nations-unies-ont-75-ans\/#article","isPartOf":{"@id":"https:\/\/apnu.be\/index.php\/2020\/10\/21\/24-octobre-les-nations-unies-ont-75-ans\/"},"author":{"name":"admin","@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc"},"headline":"24 octobre 2020: les Nations Unies ont eu 75 ans","datePublished":"2020-10-21T16:46:05+00:00","dateModified":"2021-09-19T16:12:35+00:00","mainEntityOfPage":{"@id":"https:\/\/apnu.be\/index.php\/2020\/10\/21\/24-octobre-les-nations-unies-ont-75-ans\/"},"wordCount":292,"commentCount":0,"image":{"@id":"https:\/\/apnu.be\/index.php\/2020\/10\/21\/24-octobre-les-nations-unies-ont-75-ans\/#primaryimage"},"thumbnailUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2020\/10\/un75_fr-e1603563920448.jpg","articleSection":["\u00c0 ne pas manquer"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/apnu.be\/index.php\/2020\/10\/21\/24-octobre-les-nations-unies-ont-75-ans\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/apnu.be\/index.php\/2020\/10\/21\/24-octobre-les-nations-unies-ont-75-ans\/","url":"https:\/\/apnu.be\/index.php\/2020\/10\/21\/24-octobre-les-nations-unies-ont-75-ans\/","name":"24 octobre 2020: les Nations Unies ont eu 75 ans - APNU","isPartOf":{"@id":"https:\/\/apnu.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apnu.be\/index.php\/2020\/10\/21\/24-octobre-les-nations-unies-ont-75-ans\/#primaryimage"},"image":{"@id":"https:\/\/apnu.be\/index.php\/2020\/10\/21\/24-octobre-les-nations-unies-ont-75-ans\/#primaryimage"},"thumbnailUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2020\/10\/un75_fr-e1603563920448.jpg","datePublished":"2020-10-21T16:46:05+00:00","dateModified":"2021-09-19T16:12:35+00:00","author":{"@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc"},"breadcrumb":{"@id":"https:\/\/apnu.be\/index.php\/2020\/10\/21\/24-octobre-les-nations-unies-ont-75-ans\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apnu.be\/index.php\/2020\/10\/21\/24-octobre-les-nations-unies-ont-75-ans\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/apnu.be\/index.php\/2020\/10\/21\/24-octobre-les-nations-unies-ont-75-ans\/#primaryimage","url":"https:\/\/apnu.be\/wp-content\/uploads\/2020\/10\/un75_fr-e1603563920448.jpg","contentUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2020\/10\/un75_fr-e1603563920448.jpg","width":864,"height":417},{"@type":"BreadcrumbList","@id":"https:\/\/apnu.be\/index.php\/2020\/10\/21\/24-octobre-les-nations-unies-ont-75-ans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/apnu.be\/"},{"@type":"ListItem","position":2,"name":"24 octobre 2020: les Nations Unies ont eu 75 ans"}]},{"@type":"WebSite","@id":"https:\/\/apnu.be\/#website","url":"https:\/\/apnu.be\/","name":"APNU","description":"L\u2019Association pour les Nations Unies (A.P.N.U.). Association sans but lucratif (A.S.B.L.)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apnu.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/apnu.be\/index.php\/author\/admin\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/apnu.be\/wp-content\/uploads\/2020\/10\/un75_fr-e1603563920448.jpg","_links":{"self":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/8952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/comments?post=8952"}],"version-history":[{"count":6,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/8952\/revisions"}],"predecessor-version":[{"id":9447,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/8952\/revisions\/9447"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/media\/8958"}],"wp:attachment":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/media?parent=8952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/categories?post=8952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/tags?post=8952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}