{"id":8762,"date":"2020-05-24T09:26:11","date_gmt":"2020-05-24T07:26:11","guid":{"rendered":"https:\/\/apnu.be\/?p=8762"},"modified":"2021-09-19T17:22:03","modified_gmt":"2021-09-19T15:22:03","slug":"le-covid-19-et-le-monde-du-travail","status":"publish","type":"post","link":"https:\/\/apnu.be\/index.php\/2020\/05\/24\/le-covid-19-et-le-monde-du-travail\/","title":{"rendered":"Le COVID-19 et le monde du travail"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le monde du travail est profond\u00e9ment touch\u00e9 par la pand\u00e9mie mondiale du Coronavirus. Outre la menace que cela repr\u00e9sente pour la sant\u00e9 publique, les bouleversements \u00e9conomiques et sociaux menacent les moyens de subsistance et le bien-\u00eatre \u00e0 long terme de millions d\u2019individus. L\u2019OIT et ses mandants \u2013 gouvernements, employeurs et travailleurs \u2013 joueront un r\u00f4le primordial dans la lutte contre la pand\u00e9mie en garantissant la s\u00e9curit\u00e9 des personnes ainsi que la viabilit\u00e9 des entreprises et des emplois.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">GEN\u00c8VE (OIT Infos) \u2013 La poursuite de la baisse significative du nombre d\u2019heures travaill\u00e9es dans le monde en raison du&nbsp;<a href=\"https:\/\/www.ilo.org\/global\/topics\/coronavirus\/lang--fr\/index.htm\">COVID-19&nbsp;<\/a>&nbsp;a pour cons\u00e9quence que 1,6 milliard de travailleurs de l\u2019\u00e9conomie informelle \u2013 soit pr\u00e8s de la moiti\u00e9 de la main-d\u2019\u0153uvre mondiale \u2013 doivent d\u00e9sormais faire face au danger imm\u00e9diat de voir leurs moyens de subsistance an\u00e9antis, avertit l\u2019Organisation internationale du Travail (OIT).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Selon la note&nbsp;<em><a href=\"https:\/\/www.ilo.org\/wcmsp5\/groups\/public\/---dgreports\/---dcomm\/documents\/briefingnote\/wcms_743155.pdf\">Observatoire de l\u2019OIT: le COVID-19 et le monde du travail 3e \u00e9dition&nbsp;<\/a><\/em>, la baisse du nombre d\u2019heures travaill\u00e9es pour le trimestre en cours (deuxi\u00e8me trimestre 2020) devrait s\u2019aggraver de mani\u00e8re significative par rapport \u00e0 l\u2019estimation pr\u00e9c\u00e9dente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si l\u2019on compare aux niveaux d\u2019avant la crise (4e trimestre 2019), une baisse de 10,5 pour cent est attendue, \u00e9quivalente \u00e0 305 millions d\u2019emplois \u00e0 temps plein (avec comme base une semaine de travail de 48 heures). L\u2019estimation pr\u00e9c\u00e9dente pr\u00e9voyait une chute de 6,7 pour cent, \u00e9quivalente \u00e0 195 millions de travailleurs \u00e0 temps plein. Ceci est la cons\u00e9quence de la prolongation et de l\u2019extension des mesures de confinement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La plupart du temps, la situation a empir\u00e9 au niveau r\u00e9gional. Dans les Am\u00e9riques, l\u2019estimation s\u2019\u00e9tablit \u00e0 12,4 pour cent de perte d\u2019heures travaill\u00e9es au 2e trimestre (si l\u2019on compare aux niveaux d\u2019avant la crise). Elle est de 11,8 pour cent pour l\u2019Europe et l\u2019Asie centrale. Les estimations pour les autres r\u00e9gions du monde sont assez proches, toutes \u00e9tant sup\u00e9rieures \u00e0 9,5 pour cent.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cons\u00e9quences sur l\u2019\u00e9conomie informelle<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En raison de la crise \u00e9conomique cr\u00e9\u00e9e par la pand\u00e9mie, pr\u00e8s de 1,6 milliard de travailleurs de l\u2019\u00e9conomie informelle (repr\u00e9sentant les plus vuln\u00e9rables sur le march\u00e9 du travail) ont subi une r\u00e9duction s\u00e9v\u00e8re de leurs capacit\u00e9s \u00e0 gagner leur vie, sur un total mondial de 2 milliards et une main-d\u2019\u0153uvre mondiale de 3,3 milliards. Il s\u2019agit d\u2019une cons\u00e9quence des mesures de confinement et\/ou en raison du fait qu\u2019ils travaillent dans les secteurs les plus touch\u00e9s.<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"L\u2019impact du COVID-19 sur l\u2019\u00e9conomie  informelle\" width=\"780\" height=\"585\" src=\"https:\/\/www.youtube.com\/embed\/Zm8JCMdRbrI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">On estime que le premier mois de la crise a entra\u00een\u00e9 une baisse de 60 pour cent du revenu des travailleurs informels dans le monde. Cela se traduit par une chute de 81 pour cent en Afrique et dans les Am\u00e9riques, 21,6 pour cent en Asie et Pacifique et 70 pour cent en Europe et en Asie centrale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sans sources de revenus alternatives, ces travailleurs et leurs familles n\u2019auront plus de moyens de subsistance.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Entreprises en p\u00e9ril<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La proportion des travailleurs vivant dans des pays o\u00f9 les lieux de travail font l\u2019objet d\u2019une fermeture obligatoire ou recommand\u00e9e est en baisse de 81 \u00e0 68 pour cent ces quinze derniers jours. Cette baisse par rapport \u00e0 l\u2019estimation pr\u00e9c\u00e9dente de 81 pour cent mentionn\u00e9e dans la&nbsp;<a href=\"https:\/\/www.ilo.org\/wcmsp5\/groups\/public\/---dgreports\/---dcomm\/documents\/briefingnote\/wcms_740982.pdf\">deuxi\u00e8me \u00e9dition de l\u2019Observatoire&nbsp;<\/a>&nbsp;(publi\u00e9e le 7 avril) a pour cause principale les changements intervenus en Chine. Ailleurs, les mesures de fermeture des lieux de travail sont en augmentation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au niveau mondial, plus de 436 millions d\u2019entreprises font face \u00e0 des risques \u00e9lev\u00e9s de perturbations. Ces derni\u00e8res exercent leur activit\u00e9 dans les secteurs \u00e9conomiques les plus touch\u00e9s, comme c\u2019est le cas de 232 millions d\u2019entre elles dans la vente en gros et au d\u00e9tail, 111 millions dans l\u2019industrie, 51 millions dans l\u2019h\u00f4tellerie et la restauration, et 42 millions dans l\u2019immobilier et d\u2019autres activit\u00e9s commerciales.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">N\u00e9cessit\u00e9 de mesures urgentes<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019OIT appelle \u00e0 des mesures urgentes, cibl\u00e9es et souples afin de soutenir les travailleurs et les entreprises, notamment les petites entreprises, ceux qui exercent leur activit\u00e9 dans l\u2019\u00e9conomie informelle ainsi que les autres personnes vuln\u00e9rables.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cPour des millions de travailleurs, l\u2019absence de revenus signifie plus rien \u00e0 manger, et l\u2019absence totale de s\u00e9curit\u00e9 et d\u2019avenir. [&#8230;] Au fur et \u00e0 mesure de l\u2019\u00e9volution de la pand\u00e9mie et de la crise de l\u2019emploi, le besoin de prot\u00e9ger les plus vuln\u00e9rables devient de plus en plus pressant.\u00bb<\/p><cite>Guy Ryder, Directeur g\u00e9n\u00e9ral de l&rsquo;OIT<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Ces mesures de relance \u00e9conomique doivent \u00eatre g\u00e9n\u00e9ratrices d\u2019emplois, soutenues par des politiques et des institutions du travail plus robustes, et des syst\u00e8mes de protection sociale mieux financ\u00e9s et plus complets. Une coordination internationale au niveau des mesures de relance et d\u2019all\u00e9gement de la dette est \u00e9galement essentielle pour rendre la reprise \u00e9conomique optimale et durable. Les normes internationales du travail, qui b\u00e9n\u00e9ficient d\u00e9j\u00e0 d\u2019un consentement tripartite, peuvent servir de cadre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abAu fur et \u00e0 mesure de l\u2019\u00e9volution de la pand\u00e9mie et de la crise de l\u2019emploi, le besoin de prot\u00e9ger les plus vuln\u00e9rables devient de plus en plus pressant\u00bb, affirme Guy Ryder, Directeur g\u00e9n\u00e9ral de l\u2019OIT. \u00abPour des millions de travailleurs, l\u2019absence de revenus signifie plus rien \u00e0 manger, et l\u2019absence totale de s\u00e9curit\u00e9 et d\u2019avenir. Des millions d\u2019entreprises \u00e0 travers le monde ont du mal \u00e0 tenir la t\u00eate hors de l\u2019eau. Elles n\u2019ont pas d\u2019\u00e9pargne ou pas d\u2019acc\u00e8s au cr\u00e9dit. Voil\u00e0 pourtant le vrai visage du monde du travail. Si nous ne leur venons pas en aide d\u00e8s \u00e0 pr\u00e9sent, elles vont dispara\u00eetre, tout simplement.\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le monde du travail est profond\u00e9ment touch\u00e9 par la pand\u00e9mie mondiale du Coronavirus. Outre la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":8764,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[118],"tags":[],"class_list":["post-8762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le COVID-19 et le monde du travail - APNU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apnu.be\/index.php\/2020\/05\/24\/le-covid-19-et-le-monde-du-travail\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le COVID-19 et le monde du travail - APNU\" \/>\n<meta property=\"og:description\" content=\"Le monde du travail est profond\u00e9ment touch\u00e9 par la pand\u00e9mie mondiale du Coronavirus. Outre la...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apnu.be\/index.php\/2020\/05\/24\/le-covid-19-et-le-monde-du-travail\/\" \/>\n<meta property=\"og:site_name\" content=\"APNU\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-24T07:26:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-19T15:22:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apnu.be\/wp-content\/uploads\/2020\/05\/Le-covid-et-le-monde-du-travail.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"767\" \/>\n\t<meta property=\"og:image:height\" content=\"431\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/05\\\/24\\\/le-covid-19-et-le-monde-du-travail\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/05\\\/24\\\/le-covid-19-et-le-monde-du-travail\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\"},\"headline\":\"Le COVID-19 et le monde du travail\",\"datePublished\":\"2020-05-24T07:26:11+00:00\",\"dateModified\":\"2021-09-19T15:22:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/05\\\/24\\\/le-covid-19-et-le-monde-du-travail\\\/\"},\"wordCount\":996,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/05\\\/24\\\/le-covid-19-et-le-monde-du-travail\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Le-covid-et-le-monde-du-travail.jpg\",\"articleSection\":[\"Articles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/05\\\/24\\\/le-covid-19-et-le-monde-du-travail\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/05\\\/24\\\/le-covid-19-et-le-monde-du-travail\\\/\",\"url\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/05\\\/24\\\/le-covid-19-et-le-monde-du-travail\\\/\",\"name\":\"Le COVID-19 et le monde du travail - APNU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/05\\\/24\\\/le-covid-19-et-le-monde-du-travail\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/05\\\/24\\\/le-covid-19-et-le-monde-du-travail\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Le-covid-et-le-monde-du-travail.jpg\",\"datePublished\":\"2020-05-24T07:26:11+00:00\",\"dateModified\":\"2021-09-19T15:22:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/05\\\/24\\\/le-covid-19-et-le-monde-du-travail\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/05\\\/24\\\/le-covid-19-et-le-monde-du-travail\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/05\\\/24\\\/le-covid-19-et-le-monde-du-travail\\\/#primaryimage\",\"url\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Le-covid-et-le-monde-du-travail.jpg\",\"contentUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Le-covid-et-le-monde-du-travail.jpg\",\"width\":767,\"height\":431},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2020\\\/05\\\/24\\\/le-covid-19-et-le-monde-du-travail\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/apnu.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le COVID-19 et le monde du travail\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#website\",\"url\":\"https:\\\/\\\/apnu.be\\\/\",\"name\":\"APNU\",\"description\":\"L\u2019Association pour les Nations Unies (A.P.N.U.). Association sans but lucratif (A.S.B.L.)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apnu.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le COVID-19 et le monde du travail - APNU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apnu.be\/index.php\/2020\/05\/24\/le-covid-19-et-le-monde-du-travail\/","og_locale":"fr_FR","og_type":"article","og_title":"Le COVID-19 et le monde du travail - APNU","og_description":"Le monde du travail est profond\u00e9ment touch\u00e9 par la pand\u00e9mie mondiale du Coronavirus. Outre la...","og_url":"https:\/\/apnu.be\/index.php\/2020\/05\/24\/le-covid-19-et-le-monde-du-travail\/","og_site_name":"APNU","article_published_time":"2020-05-24T07:26:11+00:00","article_modified_time":"2021-09-19T15:22:03+00:00","og_image":[{"width":767,"height":431,"url":"https:\/\/apnu.be\/wp-content\/uploads\/2020\/05\/Le-covid-et-le-monde-du-travail.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/apnu.be\/index.php\/2020\/05\/24\/le-covid-19-et-le-monde-du-travail\/#article","isPartOf":{"@id":"https:\/\/apnu.be\/index.php\/2020\/05\/24\/le-covid-19-et-le-monde-du-travail\/"},"author":{"name":"admin","@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc"},"headline":"Le COVID-19 et le monde du travail","datePublished":"2020-05-24T07:26:11+00:00","dateModified":"2021-09-19T15:22:03+00:00","mainEntityOfPage":{"@id":"https:\/\/apnu.be\/index.php\/2020\/05\/24\/le-covid-19-et-le-monde-du-travail\/"},"wordCount":996,"commentCount":0,"image":{"@id":"https:\/\/apnu.be\/index.php\/2020\/05\/24\/le-covid-19-et-le-monde-du-travail\/#primaryimage"},"thumbnailUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2020\/05\/Le-covid-et-le-monde-du-travail.jpg","articleSection":["Articles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/apnu.be\/index.php\/2020\/05\/24\/le-covid-19-et-le-monde-du-travail\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/apnu.be\/index.php\/2020\/05\/24\/le-covid-19-et-le-monde-du-travail\/","url":"https:\/\/apnu.be\/index.php\/2020\/05\/24\/le-covid-19-et-le-monde-du-travail\/","name":"Le COVID-19 et le monde du travail - APNU","isPartOf":{"@id":"https:\/\/apnu.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apnu.be\/index.php\/2020\/05\/24\/le-covid-19-et-le-monde-du-travail\/#primaryimage"},"image":{"@id":"https:\/\/apnu.be\/index.php\/2020\/05\/24\/le-covid-19-et-le-monde-du-travail\/#primaryimage"},"thumbnailUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2020\/05\/Le-covid-et-le-monde-du-travail.jpg","datePublished":"2020-05-24T07:26:11+00:00","dateModified":"2021-09-19T15:22:03+00:00","author":{"@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc"},"breadcrumb":{"@id":"https:\/\/apnu.be\/index.php\/2020\/05\/24\/le-covid-19-et-le-monde-du-travail\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apnu.be\/index.php\/2020\/05\/24\/le-covid-19-et-le-monde-du-travail\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/apnu.be\/index.php\/2020\/05\/24\/le-covid-19-et-le-monde-du-travail\/#primaryimage","url":"https:\/\/apnu.be\/wp-content\/uploads\/2020\/05\/Le-covid-et-le-monde-du-travail.jpg","contentUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2020\/05\/Le-covid-et-le-monde-du-travail.jpg","width":767,"height":431},{"@type":"BreadcrumbList","@id":"https:\/\/apnu.be\/index.php\/2020\/05\/24\/le-covid-19-et-le-monde-du-travail\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/apnu.be\/"},{"@type":"ListItem","position":2,"name":"Le COVID-19 et le monde du travail"}]},{"@type":"WebSite","@id":"https:\/\/apnu.be\/#website","url":"https:\/\/apnu.be\/","name":"APNU","description":"L\u2019Association pour les Nations Unies (A.P.N.U.). Association sans but lucratif (A.S.B.L.)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apnu.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/apnu.be\/index.php\/author\/admin\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/apnu.be\/wp-content\/uploads\/2020\/05\/Le-covid-et-le-monde-du-travail.jpg","_links":{"self":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/8762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/comments?post=8762"}],"version-history":[{"count":2,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/8762\/revisions"}],"predecessor-version":[{"id":8766,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/8762\/revisions\/8766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/media\/8764"}],"wp:attachment":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/media?parent=8762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/categories?post=8762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/tags?post=8762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}