{"id":10570,"date":"2025-10-14T11:31:56","date_gmt":"2025-10-14T09:31:56","guid":{"rendered":"https:\/\/apnu.be\/?p=10570"},"modified":"2025-11-20T12:07:49","modified_gmt":"2025-11-20T11:07:49","slug":"10570","status":"publish","type":"post","link":"https:\/\/apnu.be\/index.php\/2025\/10\/14\/10570\/","title":{"rendered":"Conf\u00e9rence\/d\u00e9bat: \u00ab\u00a0Vers une gouvernance mondiale de l&rsquo;IA, le r\u00f4le des Nations Unies\u00a0\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Le 19 novembre 2025 \u00e0 18h30 \u00e0 la Fondation universitaire, 11 rue d&rsquo;Egmont, 1000 Bruxelles<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ev\u00e8nement gratuit ouvert \u00e0 toutes et tous. Inscription<a href=\"https:\/\/link.mail.beehiiv.com\/ss\/c\/u001.i1KMfW-zsi_RGj7U54nIMqqSXXbXfi5VvQUzCs2vKY4bxuv1ok3YvT-d6rsfnM7cDwSvraJDAHo1_Al-YwhUVlSAP2CVTYcSFJQs8VM6Jz9VYJw_sB-BM0jRsjEgCNmBKJSuUdf1Orv6z9YsUI1s8NQ6TtZ_uWi6RbKZa4tEZmB4cz3idkIwxweKBjXSCgDzseDDyYQ4PIpYbU6p5tbLlXyuCyLhSCpYPgt7Yv5Q6nsCorXJW57rWjBpeFhdF8Kg\/4ko\/p__nthWNSYKhacHsASmOAg\/h2\/h001.GIoYmm-zEBrksSCEtDro4SIV9-xrA_UG_qgwUpj9OV8\"> ici<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Depuis 1946, l\u2019ONU produit des normes universelles, qui g\u00e9n\u00e8rent des engagements et des obligations pour les Etats membres et organisent leur coop\u00e9ration, sur des sujets aussi divers que les droits humains ou le d\u00e9sarmement, mais aussi, plus r\u00e9cemment, la protection du climat ou la gestion des pand\u00e9mies. Elle a r\u00e9cemment instaur\u00e9 un \u00ab&nbsp; Dialogue mondial sur la coop\u00e9ration et la gouvernance de l\u2019intelligence artificielle au b\u00e9n\u00e9fice de tous \u00bb.<br><br>Si les avanc\u00e9es rapides de l\u2019IA ouvrent quantit\u00e9 de nouvelles perspectives, elles suscitent aussi de nombreuses inqui\u00e9tudes et des appels \u00e0 une meilleure r\u00e9gulation. Pour un d\u00e9veloppement et des usages de l\u2019IA respectueux des droits humains, de l\u2019\u00e9tat de droit et de l\u2019environnement, au b\u00e9n\u00e9fice de chacune et de chacun, quelle gouvernance envisager au niveau mondial?&nbsp; De quels mod\u00e8les s\u2019inspirer? Quel r\u00f4le l\u2019ONU est-elle appel\u00e9e \u00e0 jouer ?<\/td><\/tr><tr><td>Rendez-vous le 19 novembre pour en discuter avec des experts:<br><br><strong>Pr. Hugues Bersini<\/strong>, Professeur d\u2019informatique et d\u2019IA \u00e0 l\u2019ULB, Directeur de l\u2019institut IRIDIA (IA de l\u2019ULB) et co-cr\u00e9ateur de l\u2019Institut FARI (IA pour les biens publics bruxellois)<br><strong>Dr. Lucilla Sioli<\/strong>, Directrice du \u00ab EU AI Office \u00bb au sein de la Direction g\u00e9n\u00e9rale CONNECT de la Commission europ\u00e9enne, responsable de la coordination de la Strat\u00e9gie europ\u00e9enne sur l\u2019intelligence artificielle et sa gouvernance.<br><strong>Dr. Luigia di Gisi<\/strong>, Liaison Officer (Sciences humaines et sociales), Bureau de liaison de l\u2019UNESCO \u00e0 Bruxelles et Repr\u00e9sentation aupr\u00e8s de l\u2019UE<\/td><\/tr><tr><td>L\u2019\u00e9v\u00e9nement est gratuit. Pour des raisons pratiques, merci de vous inscrire.<\/td><\/tr><tr><td>Pour toute question, contactez&nbsp;<a href=\"mailto:secretaire@apnu.be\" rel=\"noreferrer noopener\" target=\"_blank\">secretaire@apnu.be<\/a>.<\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Le 19 novembre 2025 \u00e0 18h30 \u00e0 la Fondation universitaire, 11 rue d&rsquo;Egmont, 1000 Bruxelles&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":10578,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[108],"tags":[],"class_list":["post-10570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conferences"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conf\u00e9rence\/d\u00e9bat: &quot;Vers une gouvernance mondiale de l&#039;IA, le r\u00f4le des Nations Unies&quot; - APNU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apnu.be\/index.php\/2025\/10\/14\/10570\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conf\u00e9rence\/d\u00e9bat: &quot;Vers une gouvernance mondiale de l&#039;IA, le r\u00f4le des Nations Unies&quot; - APNU\" \/>\n<meta property=\"og:description\" content=\"Le 19 novembre 2025 \u00e0 18h30 \u00e0 la Fondation universitaire, 11 rue d&rsquo;Egmont, 1000 Bruxelles....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apnu.be\/index.php\/2025\/10\/14\/10570\/\" \/>\n<meta property=\"og:site_name\" content=\"APNU\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-14T09:31:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-20T11:07:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apnu.be\/wp-content\/uploads\/2025\/10\/Conference-IA-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1409\" \/>\n\t<meta property=\"og:image:height\" content=\"765\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2025\\\/10\\\/14\\\/10570\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2025\\\/10\\\/14\\\/10570\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\"},\"headline\":\"Conf\u00e9rence\\\/d\u00e9bat: \u00ab\u00a0Vers une gouvernance mondiale de l&rsquo;IA, le r\u00f4le des Nations Unies\u00a0\u00bb\",\"datePublished\":\"2025-10-14T09:31:56+00:00\",\"dateModified\":\"2025-11-20T11:07:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2025\\\/10\\\/14\\\/10570\\\/\"},\"wordCount\":323,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2025\\\/10\\\/14\\\/10570\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Conference-IA-2.jpg\",\"articleSection\":[\"Conf\u00e9rences\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/apnu.be\\\/index.php\\\/2025\\\/10\\\/14\\\/10570\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2025\\\/10\\\/14\\\/10570\\\/\",\"url\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2025\\\/10\\\/14\\\/10570\\\/\",\"name\":\"Conf\u00e9rence\\\/d\u00e9bat: \\\"Vers une gouvernance mondiale de l'IA, le r\u00f4le des Nations Unies\\\" - APNU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2025\\\/10\\\/14\\\/10570\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2025\\\/10\\\/14\\\/10570\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Conference-IA-2.jpg\",\"datePublished\":\"2025-10-14T09:31:56+00:00\",\"dateModified\":\"2025-11-20T11:07:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2025\\\/10\\\/14\\\/10570\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apnu.be\\\/index.php\\\/2025\\\/10\\\/14\\\/10570\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2025\\\/10\\\/14\\\/10570\\\/#primaryimage\",\"url\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Conference-IA-2.jpg\",\"contentUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Conference-IA-2.jpg\",\"width\":1409,\"height\":765},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2025\\\/10\\\/14\\\/10570\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/apnu.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conf\u00e9rence\\\/d\u00e9bat: \u00ab\u00a0Vers une gouvernance mondiale de l&rsquo;IA, le r\u00f4le des Nations Unies\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#website\",\"url\":\"https:\\\/\\\/apnu.be\\\/\",\"name\":\"APNU\",\"description\":\"L\u2019Association pour les Nations Unies (A.P.N.U.). Association sans but lucratif (A.S.B.L.)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apnu.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conf\u00e9rence\/d\u00e9bat: \"Vers une gouvernance mondiale de l'IA, le r\u00f4le des Nations Unies\" - APNU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apnu.be\/index.php\/2025\/10\/14\/10570\/","og_locale":"fr_FR","og_type":"article","og_title":"Conf\u00e9rence\/d\u00e9bat: \"Vers une gouvernance mondiale de l'IA, le r\u00f4le des Nations Unies\" - APNU","og_description":"Le 19 novembre 2025 \u00e0 18h30 \u00e0 la Fondation universitaire, 11 rue d&rsquo;Egmont, 1000 Bruxelles....","og_url":"https:\/\/apnu.be\/index.php\/2025\/10\/14\/10570\/","og_site_name":"APNU","article_published_time":"2025-10-14T09:31:56+00:00","article_modified_time":"2025-11-20T11:07:49+00:00","og_image":[{"width":1409,"height":765,"url":"https:\/\/apnu.be\/wp-content\/uploads\/2025\/10\/Conference-IA-2.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/apnu.be\/index.php\/2025\/10\/14\/10570\/#article","isPartOf":{"@id":"https:\/\/apnu.be\/index.php\/2025\/10\/14\/10570\/"},"author":{"name":"admin","@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc"},"headline":"Conf\u00e9rence\/d\u00e9bat: \u00ab\u00a0Vers une gouvernance mondiale de l&rsquo;IA, le r\u00f4le des Nations Unies\u00a0\u00bb","datePublished":"2025-10-14T09:31:56+00:00","dateModified":"2025-11-20T11:07:49+00:00","mainEntityOfPage":{"@id":"https:\/\/apnu.be\/index.php\/2025\/10\/14\/10570\/"},"wordCount":323,"commentCount":0,"image":{"@id":"https:\/\/apnu.be\/index.php\/2025\/10\/14\/10570\/#primaryimage"},"thumbnailUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2025\/10\/Conference-IA-2.jpg","articleSection":["Conf\u00e9rences"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/apnu.be\/index.php\/2025\/10\/14\/10570\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/apnu.be\/index.php\/2025\/10\/14\/10570\/","url":"https:\/\/apnu.be\/index.php\/2025\/10\/14\/10570\/","name":"Conf\u00e9rence\/d\u00e9bat: \"Vers une gouvernance mondiale de l'IA, le r\u00f4le des Nations Unies\" - APNU","isPartOf":{"@id":"https:\/\/apnu.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apnu.be\/index.php\/2025\/10\/14\/10570\/#primaryimage"},"image":{"@id":"https:\/\/apnu.be\/index.php\/2025\/10\/14\/10570\/#primaryimage"},"thumbnailUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2025\/10\/Conference-IA-2.jpg","datePublished":"2025-10-14T09:31:56+00:00","dateModified":"2025-11-20T11:07:49+00:00","author":{"@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc"},"breadcrumb":{"@id":"https:\/\/apnu.be\/index.php\/2025\/10\/14\/10570\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apnu.be\/index.php\/2025\/10\/14\/10570\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/apnu.be\/index.php\/2025\/10\/14\/10570\/#primaryimage","url":"https:\/\/apnu.be\/wp-content\/uploads\/2025\/10\/Conference-IA-2.jpg","contentUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2025\/10\/Conference-IA-2.jpg","width":1409,"height":765},{"@type":"BreadcrumbList","@id":"https:\/\/apnu.be\/index.php\/2025\/10\/14\/10570\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/apnu.be\/"},{"@type":"ListItem","position":2,"name":"Conf\u00e9rence\/d\u00e9bat: \u00ab\u00a0Vers une gouvernance mondiale de l&rsquo;IA, le r\u00f4le des Nations Unies\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/apnu.be\/#website","url":"https:\/\/apnu.be\/","name":"APNU","description":"L\u2019Association pour les Nations Unies (A.P.N.U.). Association sans but lucratif (A.S.B.L.)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apnu.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/apnu.be\/index.php\/author\/admin\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/apnu.be\/wp-content\/uploads\/2025\/10\/Conference-IA-2.jpg","_links":{"self":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/10570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/comments?post=10570"}],"version-history":[{"count":4,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/10570\/revisions"}],"predecessor-version":[{"id":10672,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/10570\/revisions\/10672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/media\/10578"}],"wp:attachment":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/media?parent=10570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/categories?post=10570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/tags?post=10570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}