{"id":10256,"date":"2024-06-28T10:07:52","date_gmt":"2024-06-28T08:07:52","guid":{"rendered":"https:\/\/apnu.be\/?p=10256"},"modified":"2024-06-28T10:23:04","modified_gmt":"2024-06-28T08:23:04","slug":"responsabilite-climatique-apnu-dossier-climat","status":"publish","type":"post","link":"https:\/\/apnu.be\/index.php\/2024\/06\/28\/responsabilite-climatique-apnu-dossier-climat\/","title":{"rendered":"Carte Blanche &#8211; La nuance dans le dossier climat reste d\u2019importance capitale\u00a0\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">______________________________\u00a0\u00a0<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\">Oui, chacun de nous porte une responsabilit\u00e9 climatique dans son comportement quotidien.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-2 wp-block-paragraph\">Oui, l\u2019inaction de l\u2019autre n\u2019est en aucun cas une excuse pour ne pas assumer sa propre responsabilit\u00e9.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-3 wp-block-paragraph\">Oui, les pays d\u00e9velopp\u00e9s n\u2019ont pas le droit d\u2019\u00eatre des donneurs de le\u00e7on \u00e0 des pays en plein d\u00e9veloppement.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-4 wp-block-paragraph\">Heureusement, une tranche importante de la nouvelle g\u00e9n\u00e9ration chez nous a d\u00e9cid\u00e9 de vivre bien plus sobrement que les g\u00e9n\u00e9rations pr\u00e9c\u00e9dentes, de renoncer totalement \u00e0 la voiture, et de ne plus prendre l\u2019avion. Moi aussi j\u2019ai adapt\u00e9 mon comportement, en passant bient\u00f4t \u00e0 une petite voiture \u00e9lectrique et \u00e9tant devenu v\u00e9g\u00e9tarien.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-5 wp-block-paragraph\">Mais devons-nous pour autant soutenir une massive auto-culpabilisation\u202f? Le pendule ne commence-t-il pas \u00e0 aller trop\u202floin, sans contrepartie suffisante ailleurs\u202fdans le monde ?&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-6 wp-block-paragraph\">L\u2019Agence Internationale de l\u2019Energie \u00e9crivait en 2023: \u00ab\u00a0<em>The landscape of emissions continues to change. China\u2019s total CO<sub>2<\/sub>\u202femissions exceeded those of the advanced economies combined in 2020, and in 2023 were 15% higher. India surpassed the European Union to become the third largest source of global emissions in 2023. Countries in developing Asia now account for around half of global emissions, up from around two-fifths in 2015 and around onequarter in 2000. China alone accounts for 35% of global CO<sub>2<\/sub>\u202femissions<\/em>\u00ab\u00a0.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-7 wp-block-paragraph\">Concentrons-nous un instant sur le charbon.\u202fLa Chine, malgr\u00e9 des efforts impressionnants sur les renouvelables, \u00e9mettait en 2023 5,5 milliards de tonnes de CO2 via sa production d\u2019\u00e9nergie sur base de charbon, un record dans ses statistiques, et d\u00e9passant de 6 pct leur pr\u00e9c\u00e9dent record national de 2022.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-8 wp-block-paragraph\">L\u2019Australie exportait toujours 335 millions de tonnes de charbon en 2022-2023.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-9 wp-block-paragraph\">En Arabie saoudite, un projet gargantuesque \u00ab\u202fThe Line \u202f\u00bb est en construction\u202f: une ville de 100 miles de long, dans le d\u00e9sert. Elle se veut devenir totalement \u00ab eco friendly \u00bb. Mais entretemps des experts estiment les \u00e9missions li\u00e9es \u00e0 son chantier aux dimensions bibliques, \u00e0 1,8 gigatonne de CO2\u202f!&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-10 wp-block-paragraph\">Le Qatar a les plus hautes \u00e9missions de CO2 pro capita\u202favec 37.6 tonnes par personne, \u00e0 comparer par exemple&nbsp; avec les 9 tonnes par personne pour la Belgique.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-11 wp-block-paragraph\">Dubai entame la construction d\u2019un nouvel a\u00e9roport international, qui ambitionne de devenir le plus grand du monde avec une capacit\u00e9 de 400 portes d\u2019embarquement et 250 millions de voyageurs par an.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-12 wp-block-paragraph\">Chez Total Energies, malgr\u00e9 leur engagement de r\u00e9aliser \u00ab\u202fnet zero emissions\u202f\u00bb en 2050, les \u00e9nergies fossiles repr\u00e9sentent toujours 98% de leur portefeuille, et ils ont tout r\u00e9cemment annonc\u00e9 d\u2019augmenter la production fossile sur les cinq ans \u00e0 venir.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-13 wp-block-paragraph\">Les exemples sont l\u00e9gion. Le d\u00e9s\u00e9quilibre entre la gravit\u00e9 de ces grandes sources d\u2019\u00e9mission d\u2019un c\u00f4t\u00e9, et le fait que les citoyens chez nous se morfondent dans leur culpabilit\u00e9, ne devient-il pas insupportable\u202f?&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-14 wp-block-paragraph\">Parfois, et j\u2018insiste vraiment sur ce mot, cette auto-culpabilisation est nourrie par des chiffres alarmants qu\u2019il convient de regarder deux fois plut\u00f4t qu\u2019une. Ainsi nous avons lu dans la presse r\u00e9cente que la Belgique serait le 9me pays au monde en termes de pollution CO2 par habitant. <a href=\"https:\/\/www.demorgen.be\/snelnieuws\/belgie-staat-wereldwijd-op-negende-plaats-qua-uitstoot-per-inwoner-en-dat-komt-vooral-door-rijkste-belgen~b08c35d5\/\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Voir l&rsquo;article DeMorgen<\/mark><\/a>.<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-15 wp-block-paragraph\">Je voudrais douter de l\u2019interpr\u00e9tation par le journalise , \u00e9tant donn\u00e9 que l\u2019on trouve plusieurs classements, o\u00f9 la Belgique est beaucoup plus bas : 34me (2), 41me (3), 38me (4), 23me (5)\u202f; celles-ci sont en plus toutes bien plus r\u00e9centes\u202fque la date trouv\u00e9e dans le lien\u202f: 2019. Il y aurait-il un peu de r\u00e9cup\u00e9ration politique par le biais de certaines statistiques ?&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-16 wp-block-paragraph\">Dans la m\u00eame veine, j\u2019ai entendu r\u00e9cemment \u00e0 une conf\u00e9rence climat un orateur connu marteler le fait que l\u2019empreinte \u00e9cologique de la Belgique, selon l\u2019importante m\u00e9thodologie du Earth Overshoot Day annuel, si d\u00e9clin\u00e9 pays par pays, mettait la BE \u00e0 la 6me place, juste apr\u00e8s les USA et les Emirats, et avant l\u2019Australie (6). Mais est-il professionnel de dire cela devant une salle de jeunes, visiblement choqu\u00e9s, sans mentionner que ceci est entre autres le r\u00e9sultat statistique du croisement de notre superficie modeste avec une densit\u00e9 de population tr\u00e8s \u00e9lev\u00e9e\u202f?&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-17 wp-block-paragraph\">En 1992, la convention cadre sur le changement climatique a \u00e9t\u00e9 sign\u00e9e \u00e0 Rio. Elle constitue toujours une vraie constitution pour tous les pays du monde. L\u2019assise la plus importante de cette convention est le principe de la \u00ab\u202fresponsabilit\u00e9 commune mais diff\u00e9renci\u00e9e\u202f\u00bb, ancrant ainsi une reconnaissance implicite, voire explicite, que les pays d\u00e9velopp\u00e9s doivent prendre le \u00ab\u202flead\u202f\u00bb de toute fa\u00e7on. Ce principe a \u00e9t\u00e9 r\u00e9p\u00e9t\u00e9 des milliers de fois dans les textes onusiens depuis lors et autant de fois dans les \u00ab\u202fconclusions climat\u202f\u00bb des conseil minist\u00e9riels de l\u2019UE, soit le Conseil des Ministres de l\u2019environnement, soit l\u00e9 Conseil Europ\u00e9en au niveau des chefs d\u2019\u00e9tat ou de gouvernement.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-18 wp-block-paragraph\">A la COP climat 20 \u00e0 Lima en 2014, les Parties ont convenu de nuancer ces \u00ab\u202f<em>common but differentiated responsibilities<\/em>\u202f\u00bb avec l\u2019ajout suivant \u00ab\u202f<em>and respective capabilities in light of different national circumstances<\/em>\u202f\u00bb, allusion au fait que certains pays \u00e9mergents sont devenus capables de r\u00e9duire leurs \u00e9missions de leur propre force\u202f!&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-19 wp-block-paragraph\">Une autre r\u00e9forme, que les citoyens ignorent, est que tous les pays sont depuis 2015 oblig\u00e9s de soumettre et de revoir p\u00e9riodiquement leurs plans nationaux. Ceci est le fruit de la COP Paris en 2015, et oblige tous les 193 pays membre des nations unies de soumettre un tel plan d\u00e9taill\u00e9, et de le revoir tous les cinq ans. Il n\u2019est donc plus du tout injuste de pointer vers une responsabilit\u00e9 de TOUS les pays\u202f! Et il est inversement inappropri\u00e9 d\u2019auto-culpabiliser les jeunes chez nous sur base de notre&nbsp; r\u00f4le pr\u00e9pond\u00e9rant dans tout le probl\u00e8me climatique.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-20 wp-block-paragraph\">Autant il est inacceptable de fuir nos responsabilit\u00e9s en pointant d\u2019autres pays du doigt, autant il est dangereux de passer le nouveau d\u00e9s\u00e9quilibre sous silence\u202f: ceci m\u00e8ne \u00e0 une inefficacit\u00e9 du syst\u00e8me mondial et \u00e0 du \u2018climate despair\u2019 chez nous. Et autant il est inacceptable de fausser les donn\u00e9es pour camoufler des \u00e9missions, autant il est dangereux de mal pr\u00e9senter les statistiques dans l\u2019autre sens.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-21 wp-block-paragraph\">H\u00e9las, les gouvernements des pays d\u00e9velopp\u00e9s seraient mal avis\u00e9s s\u2019ils critiquaient publiquement les gouvernements de ces freeriders.\u202fCela menacerait clairement les n\u00e9gociations futures. Que faire alors\u202f? Bien s\u00fbr il faut continuer avec vigueur les n\u00e9gociations annuelles sur les r\u00e8gles climat dans les COP. Bien s\u00fbr il faut une bien plus haute priorit\u00e9 pour le dossier climat dans CHAQUE n\u00e9gociation bilat\u00e9rale entre pays, et dans CHAQUE n\u00e9gociation bi-r\u00e9gionale, notamment commerciale. Et je vous invite vivement \u00e0 lire le tr\u00e8s puissant discours, de ce mois-ci, du Secr\u00e9taire G\u00e9n\u00e9ral des Nations Unies (7).&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-22 wp-block-paragraph\">Mais ici je voudrais surtout souligner l\u2019id\u00e9e qu\u2019il faudrait un nouvel homme d\u2019\u00e9tat, un philosophe venant des pays \u00e9mergents et non pas du \u2018Nord\u2019, un homme visionnaire, qui aurait l\u2019autorit\u00e9 de dire ce que nous n\u2019avons plus droit de leur dire: \u00ab\u202fNous pays \u00e9mergents, nous aussi avons une responsabilit\u00e9 colossale.\u202f\u00bb\u202fUn nouveau Ghandhi devrait se lever se , qui dirait, comme lui jadis \u00ab\u202f<em>The earth provides enough to satisfy every man&rsquo;s needs, but not every man&rsquo;s greed\u202f<\/em>\u00bb !&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Mr. Chris Vanden Bilcke, membre APNU <\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-23 wp-block-paragraph\">Comme le sugg\u00e8re l\u2019auteur, ne manquez pas le puissant <a href=\"https:\/\/www.un.org\/sg\/fr\/content\/sg\/statement\/2024-06-05\/secretary-generals-special-address-climate-action-moment-of-truth-delivered-0\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">discours du Secr\u00e9taire g\u00e9n\u00e9ral de l\u2019ONU \u00e0 l\u2019occasion de la journ\u00e9e mondiale de l\u2019environnement<\/mark><\/a> le 5 juin. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"1\">\n<li><a href=\"https:\/\/www.iea.org\/reports\/co2-emissions-in-2023\/the-changing-landscape-of-global-emissions\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.iea.org\/reports\/co2-emissions-in-2023\/the-changing-landscape-of-global-emissions<\/a>&nbsp;<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"2\">\n<li><a href=\"https:\/\/www.visualcapitalist.com\/ranked-per-capita-carbon-emissions-by-country\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.visualcapitalist.com\/ranked-per-capita-carbon-emissions-by-country\/<\/a>&nbsp;<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"3\">\n<li><a href=\"https:\/\/www.worldometers.info\/co2-emissions\/co2-emissions-per-capita\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.worldometers.info\/co2-emissions\/co2-emissions-per-capita\/<\/a>&nbsp;<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"4\">\n<li><a href=\"https:\/\/www.statista.com\/statistics\/270508\/co2emissions-per-capita-by-country\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.statista.com\/statistics\/270508\/co2emissions-per-capita-by-country<\/a>&nbsp;<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"5\">\n<li><a href=\"https:\/\/datacommons.org\/ranking\/Amount_Emissions_CarbonDioxyde_PerCapita\/Country\/?h=country%2FGHA&amp;unit=t\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/datacommons.org\/ranking\/Amount_Emissions_CarbonDioxyde_PerCapita\/Country\/?h=country%2FGHA&amp;unit=t<\/a>&nbsp;<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"6\">\n<li><a href=\"https:\/\/www.overshootday.org\/content\/uploads\/2023\/01\/Country-Overshoot-Days-2023.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.overshootday.org\/content\/uploads\/2023\/01\/Country-Overshoot-Days-2023.pdf<\/a>&nbsp;<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"7\">\n<li><a href=\"https:\/\/www.un.org\/sg\/fr\/content\/sg\/statement\/2024-06-05\/secretary-generals-special-address-climate-action-moment-of-truth-delivered\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.un.org\/sg\/fr\/content\/sg\/statement\/2024-06-05\/secretary-generals-special-address-climate-action-moment-of-truth-delivered<\/a>&nbsp;<\/li>\n<\/ol>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color has-link-color wp-elements-24 wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A propos de l&rsquo;auteur<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Pour cette \u00e9dition&nbsp;c\u2019est&nbsp;un membre de l\u2019 APNU,&nbsp;<strong>Chris Vanden Bilcke<\/strong>, Conseiller honoraire, membre du chapitre UE du Club de Rome, qui nous propose une carte blanche sur la n\u00e9cessit\u00e9 de trouver un \u00e9quilibre dans les responsabilit\u00e9s climatiques.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Chris Vanden Bilcke\u202fa \u00e9galement \u00e9t\u00e9 chef de la direction du d\u00e9veloppement durable et du changement climatique, au SPF Affaires \u00e9trang\u00e8res et Repr\u00e9sentant du Programme des Nations Unies pour l\u2019Environnement (PNUE) \u00e0 Bruxelles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce texte souligne l&rsquo;importance de la responsabilit\u00e9 climatique individuelle et collective. Il critique l&rsquo;auto-culpabilisation excessive face \u00e0 des contributions majeures de certains pays \u00e9mergents. L&rsquo;auteur appelle \u00e0 un nouvel \u00e9quilibre global, guid\u00e9 par un leader \u00e9mergent capable de souligner une responsabilit\u00e9 commune sans exon\u00e9rer les pays en d\u00e9veloppement.<\/p>\n","protected":false},"author":2,"featured_media":10257,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[118],"tags":[138,125],"class_list":["post-10256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles","tag-climat","tag-onu"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carte Blanche - La nuance dans le dossier climat reste capitale\u00a0\u00a0<\/title>\n<meta name=\"description\" content=\"Climat et responsabilit\u00e9 climatique : \u00e9quilibre entre culpabilisation individuelle et contributions majeures de pays \u00e9mergents.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apnu.be\/index.php\/2024\/06\/28\/responsabilite-climatique-apnu-dossier-climat\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carte Blanche - La nuance dans le dossier climat reste capitale\u00a0\u00a0\" \/>\n<meta property=\"og:description\" content=\"Climat et responsabilit\u00e9 climatique : \u00e9quilibre entre culpabilisation individuelle et contributions majeures de pays \u00e9mergents.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apnu.be\/index.php\/2024\/06\/28\/responsabilite-climatique-apnu-dossier-climat\/\" \/>\n<meta property=\"og:site_name\" content=\"APNU\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-28T08:07:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-28T08:23:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apnu.be\/wp-content\/uploads\/2024\/06\/PHOTOS-BULLETIN-13.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1640\" \/>\n\t<meta property=\"og:image:height\" content=\"924\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"APNU\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"APNU\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/06\\\/28\\\/responsabilite-climatique-apnu-dossier-climat\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/06\\\/28\\\/responsabilite-climatique-apnu-dossier-climat\\\/\"},\"author\":{\"name\":\"APNU\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/445fe831500fe02b58627fd24b39529b\"},\"headline\":\"Carte Blanche &#8211; La nuance dans le dossier climat reste d\u2019importance capitale\u00a0\u00a0\",\"datePublished\":\"2024-06-28T08:07:52+00:00\",\"dateModified\":\"2024-06-28T08:23:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/06\\\/28\\\/responsabilite-climatique-apnu-dossier-climat\\\/\"},\"wordCount\":1451,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/06\\\/28\\\/responsabilite-climatique-apnu-dossier-climat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/PHOTOS-BULLETIN-13.png\",\"keywords\":[\"climat\",\"ONU\"],\"articleSection\":[\"Articles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/06\\\/28\\\/responsabilite-climatique-apnu-dossier-climat\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/06\\\/28\\\/responsabilite-climatique-apnu-dossier-climat\\\/\",\"url\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/06\\\/28\\\/responsabilite-climatique-apnu-dossier-climat\\\/\",\"name\":\"Carte Blanche - La nuance dans le dossier climat reste capitale\u00a0\u00a0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/06\\\/28\\\/responsabilite-climatique-apnu-dossier-climat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/06\\\/28\\\/responsabilite-climatique-apnu-dossier-climat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/PHOTOS-BULLETIN-13.png\",\"datePublished\":\"2024-06-28T08:07:52+00:00\",\"dateModified\":\"2024-06-28T08:23:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/445fe831500fe02b58627fd24b39529b\"},\"description\":\"Climat et responsabilit\u00e9 climatique : \u00e9quilibre entre culpabilisation individuelle et contributions majeures de pays \u00e9mergents.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/06\\\/28\\\/responsabilite-climatique-apnu-dossier-climat\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/06\\\/28\\\/responsabilite-climatique-apnu-dossier-climat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/06\\\/28\\\/responsabilite-climatique-apnu-dossier-climat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/PHOTOS-BULLETIN-13.png\",\"contentUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/PHOTOS-BULLETIN-13.png\",\"width\":1640,\"height\":924},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/06\\\/28\\\/responsabilite-climatique-apnu-dossier-climat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/apnu.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carte Blanche &#8211; La nuance dans le dossier climat reste d\u2019importance capitale\u00a0\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#website\",\"url\":\"https:\\\/\\\/apnu.be\\\/\",\"name\":\"APNU\",\"description\":\"L\u2019Association pour les Nations Unies (A.P.N.U.). Association sans but lucratif (A.S.B.L.)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apnu.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/445fe831500fe02b58627fd24b39529b\",\"name\":\"APNU\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/226aedd8e4db0eb5acadd4364539d34ed1d6855ec400121818fe24c2ab397a5c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/226aedd8e4db0eb5acadd4364539d34ed1d6855ec400121818fe24c2ab397a5c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/226aedd8e4db0eb5acadd4364539d34ed1d6855ec400121818fe24c2ab397a5c?s=96&d=mm&r=g\",\"caption\":\"APNU\"},\"url\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/author\\\/apnu\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carte Blanche - La nuance dans le dossier climat reste capitale\u00a0\u00a0","description":"Climat et responsabilit\u00e9 climatique : \u00e9quilibre entre culpabilisation individuelle et contributions majeures de pays \u00e9mergents.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apnu.be\/index.php\/2024\/06\/28\/responsabilite-climatique-apnu-dossier-climat\/","og_locale":"fr_FR","og_type":"article","og_title":"Carte Blanche - La nuance dans le dossier climat reste capitale\u00a0\u00a0","og_description":"Climat et responsabilit\u00e9 climatique : \u00e9quilibre entre culpabilisation individuelle et contributions majeures de pays \u00e9mergents.","og_url":"https:\/\/apnu.be\/index.php\/2024\/06\/28\/responsabilite-climatique-apnu-dossier-climat\/","og_site_name":"APNU","article_published_time":"2024-06-28T08:07:52+00:00","article_modified_time":"2024-06-28T08:23:04+00:00","og_image":[{"width":1640,"height":924,"url":"https:\/\/apnu.be\/wp-content\/uploads\/2024\/06\/PHOTOS-BULLETIN-13.png","type":"image\/png"}],"author":"APNU","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"APNU","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/apnu.be\/index.php\/2024\/06\/28\/responsabilite-climatique-apnu-dossier-climat\/#article","isPartOf":{"@id":"https:\/\/apnu.be\/index.php\/2024\/06\/28\/responsabilite-climatique-apnu-dossier-climat\/"},"author":{"name":"APNU","@id":"https:\/\/apnu.be\/#\/schema\/person\/445fe831500fe02b58627fd24b39529b"},"headline":"Carte Blanche &#8211; La nuance dans le dossier climat reste d\u2019importance capitale\u00a0\u00a0","datePublished":"2024-06-28T08:07:52+00:00","dateModified":"2024-06-28T08:23:04+00:00","mainEntityOfPage":{"@id":"https:\/\/apnu.be\/index.php\/2024\/06\/28\/responsabilite-climatique-apnu-dossier-climat\/"},"wordCount":1451,"commentCount":0,"image":{"@id":"https:\/\/apnu.be\/index.php\/2024\/06\/28\/responsabilite-climatique-apnu-dossier-climat\/#primaryimage"},"thumbnailUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2024\/06\/PHOTOS-BULLETIN-13.png","keywords":["climat","ONU"],"articleSection":["Articles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/apnu.be\/index.php\/2024\/06\/28\/responsabilite-climatique-apnu-dossier-climat\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/apnu.be\/index.php\/2024\/06\/28\/responsabilite-climatique-apnu-dossier-climat\/","url":"https:\/\/apnu.be\/index.php\/2024\/06\/28\/responsabilite-climatique-apnu-dossier-climat\/","name":"Carte Blanche - La nuance dans le dossier climat reste capitale\u00a0\u00a0","isPartOf":{"@id":"https:\/\/apnu.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apnu.be\/index.php\/2024\/06\/28\/responsabilite-climatique-apnu-dossier-climat\/#primaryimage"},"image":{"@id":"https:\/\/apnu.be\/index.php\/2024\/06\/28\/responsabilite-climatique-apnu-dossier-climat\/#primaryimage"},"thumbnailUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2024\/06\/PHOTOS-BULLETIN-13.png","datePublished":"2024-06-28T08:07:52+00:00","dateModified":"2024-06-28T08:23:04+00:00","author":{"@id":"https:\/\/apnu.be\/#\/schema\/person\/445fe831500fe02b58627fd24b39529b"},"description":"Climat et responsabilit\u00e9 climatique : \u00e9quilibre entre culpabilisation individuelle et contributions majeures de pays \u00e9mergents.","breadcrumb":{"@id":"https:\/\/apnu.be\/index.php\/2024\/06\/28\/responsabilite-climatique-apnu-dossier-climat\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apnu.be\/index.php\/2024\/06\/28\/responsabilite-climatique-apnu-dossier-climat\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/apnu.be\/index.php\/2024\/06\/28\/responsabilite-climatique-apnu-dossier-climat\/#primaryimage","url":"https:\/\/apnu.be\/wp-content\/uploads\/2024\/06\/PHOTOS-BULLETIN-13.png","contentUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2024\/06\/PHOTOS-BULLETIN-13.png","width":1640,"height":924},{"@type":"BreadcrumbList","@id":"https:\/\/apnu.be\/index.php\/2024\/06\/28\/responsabilite-climatique-apnu-dossier-climat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/apnu.be\/"},{"@type":"ListItem","position":2,"name":"Carte Blanche &#8211; La nuance dans le dossier climat reste d\u2019importance capitale\u00a0\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/apnu.be\/#website","url":"https:\/\/apnu.be\/","name":"APNU","description":"L\u2019Association pour les Nations Unies (A.P.N.U.). Association sans but lucratif (A.S.B.L.)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apnu.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/apnu.be\/#\/schema\/person\/445fe831500fe02b58627fd24b39529b","name":"APNU","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/226aedd8e4db0eb5acadd4364539d34ed1d6855ec400121818fe24c2ab397a5c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/226aedd8e4db0eb5acadd4364539d34ed1d6855ec400121818fe24c2ab397a5c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/226aedd8e4db0eb5acadd4364539d34ed1d6855ec400121818fe24c2ab397a5c?s=96&d=mm&r=g","caption":"APNU"},"url":"https:\/\/apnu.be\/index.php\/author\/apnu\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/apnu.be\/wp-content\/uploads\/2024\/06\/PHOTOS-BULLETIN-13.png","_links":{"self":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/10256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/comments?post=10256"}],"version-history":[{"count":6,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/10256\/revisions"}],"predecessor-version":[{"id":10268,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/10256\/revisions\/10268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/media\/10257"}],"wp:attachment":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/media?parent=10256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/categories?post=10256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/tags?post=10256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}