{"id":10204,"date":"2024-01-26T10:58:22","date_gmt":"2024-01-26T09:58:22","guid":{"rendered":"https:\/\/apnu.be\/?p=10204"},"modified":"2024-03-28T17:44:56","modified_gmt":"2024-03-28T16:44:56","slug":"israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable","status":"publish","type":"post","link":"https:\/\/apnu.be\/index.php\/2024\/01\/26\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\/","title":{"rendered":"Israel-Palestine: \u00ab\u00a0la solution \u00e0 deux \u00e9tats, seul moyen de parvenir \u00e0 une paix durable\u00a0\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Alors que la guerre \u00e0 Gaza dure depuis plus de trois mois, le Secr\u00e9taire g\u00e9n\u00e9ral de l\u2019ONU, Ant\u00f3nio Guterres, a affirm\u00e9 le 23 janvier devant le Conseil de s\u00e9curit\u00e9 que la solution \u00e0 deux Etats, Isra\u00ebl et Palestine vivant c\u00f4te \u00e0 c\u00f4te dans la paix et la s\u00e9curit\u00e9, est le \u00ab\u00a0seul moyen de parvenir \u00e0 une paix durable\u00a0\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Le r\u00f4le de la communaut\u00e9 internationale est clair. Nous devons nous unir pour soutenir les Isra\u00e9liens et les Palestiniens afin qu&rsquo;ils prennent des mesures fortes en faveur d&rsquo;un v\u00e9ritable processus de paix \u00bb, a d\u00e9clar\u00e9 le chef de l\u2019ONU lors d\u2019une r\u00e9union du Conseil consacr\u00e9e \u00e0 la situation \u00e0 Gaza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Au cours des deux derni\u00e8res d\u00e9cennies, la solution \u00e0 deux \u00c9tats a \u00e9t\u00e9 critiqu\u00e9e, d\u00e9nigr\u00e9e, et laiss\u00e9e pour morte \u00e0 maintes reprises. Cependant, elle reste le seul moyen de parvenir \u00e0 une paix durable et \u00e9quitable &#8211; en Isra\u00ebl, en Palestine et dans la r\u00e9gion toute enti\u00e8re \u00bb, a-t-il ajout\u00e9. \u00ab Comme nous l&rsquo;avons vu au cours des trois derniers mois, c\u2019est aussi la seule voie pour sortir des cycles sans fin de peur, de haine et de violence \u00bb.\u00a0Selon le Secr\u00e9taire g\u00e9n\u00e9ral, \u00ab cette p\u00e9riode terrible pour les Isra\u00e9liens et les Palestiniens doit inciter les parties au conflit, ainsi que la communaut\u00e9 internationale, \u00e0 agir avec courage et d\u00e9termination pour parvenir \u00e0 une paix juste et durable \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il a jug\u00e9 \u00ab inacceptable \u00bb le rejet \u00ab clair et r\u00e9p\u00e9t\u00e9 \u00bb de la solution \u00e0 deux \u00c9tats, la semaine derni\u00e8re, \u00ab aux plus hauts niveaux du gouvernement isra\u00e9lien \u00bb. Selon lui, \u00ab ce refus, ainsi que le d\u00e9ni du droit \u00e0 un \u00c9tat au peuple palestinien, prolongeraient ind\u00e9finiment un conflit qui est devenu une menace majeure \u00e0 la paix et \u00e0 la s\u00e9curit\u00e9 mondiales \u00bb et cela \u00ab exacerberait la polarisation et encouragerait les extr\u00e9mistes du monde entier \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Le droit du peuple palestinien \u00e0 construire son propre \u00c9tat pleinement ind\u00e9pendant doit \u00eatre reconnu par tous. Et tout refus d\u2019accepter la solution \u00e0 deux \u00c9tats par l\u2019une ou l\u2019autre des parties doit \u00eatre fermement rejet\u00e9 \u00bb, a-t-il ajout\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors que la guerre \u00e0 Gaza dure depuis plus de trois mois, le Secr\u00e9taire g\u00e9n\u00e9ral&#8230;<\/p>\n","protected":false},"author":1,"featured_media":10203,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[118],"tags":[],"class_list":["post-10204","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Israel-Palestine: &quot;la solution \u00e0 deux \u00e9tats, seul moyen de parvenir \u00e0 une paix durable&quot; - APNU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apnu.be\/index.php\/2024\/01\/26\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Israel-Palestine: &quot;la solution \u00e0 deux \u00e9tats, seul moyen de parvenir \u00e0 une paix durable&quot; - APNU\" \/>\n<meta property=\"og:description\" content=\"Alors que la guerre \u00e0 Gaza dure depuis plus de trois mois, le Secr\u00e9taire g\u00e9n\u00e9ral...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apnu.be\/index.php\/2024\/01\/26\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\/\" \/>\n<meta property=\"og:site_name\" content=\"APNU\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-26T09:58:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-28T16:44:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apnu.be\/wp-content\/uploads\/2024\/01\/Conseil-de-securite.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/01\\\/26\\\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/01\\\/26\\\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\"},\"headline\":\"Israel-Palestine: \u00ab\u00a0la solution \u00e0 deux \u00e9tats, seul moyen de parvenir \u00e0 une paix durable\u00a0\u00bb\",\"datePublished\":\"2024-01-26T09:58:22+00:00\",\"dateModified\":\"2024-03-28T16:44:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/01\\\/26\\\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\\\/\"},\"wordCount\":374,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/01\\\/26\\\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Conseil-de-securite.jpg\",\"articleSection\":[\"Articles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/01\\\/26\\\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/01\\\/26\\\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\\\/\",\"url\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/01\\\/26\\\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\\\/\",\"name\":\"Israel-Palestine: \\\"la solution \u00e0 deux \u00e9tats, seul moyen de parvenir \u00e0 une paix durable\\\" - APNU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/01\\\/26\\\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/01\\\/26\\\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Conseil-de-securite.jpg\",\"datePublished\":\"2024-01-26T09:58:22+00:00\",\"dateModified\":\"2024-03-28T16:44:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/01\\\/26\\\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/01\\\/26\\\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/01\\\/26\\\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\\\/#primaryimage\",\"url\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Conseil-de-securite.jpg\",\"contentUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Conseil-de-securite.jpg\",\"width\":1170,\"height\":530},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2024\\\/01\\\/26\\\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/apnu.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Israel-Palestine: \u00ab\u00a0la solution \u00e0 deux \u00e9tats, seul moyen de parvenir \u00e0 une paix durable\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#website\",\"url\":\"https:\\\/\\\/apnu.be\\\/\",\"name\":\"APNU\",\"description\":\"L\u2019Association pour les Nations Unies (A.P.N.U.). Association sans but lucratif (A.S.B.L.)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apnu.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Israel-Palestine: \"la solution \u00e0 deux \u00e9tats, seul moyen de parvenir \u00e0 une paix durable\" - APNU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apnu.be\/index.php\/2024\/01\/26\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\/","og_locale":"fr_FR","og_type":"article","og_title":"Israel-Palestine: \"la solution \u00e0 deux \u00e9tats, seul moyen de parvenir \u00e0 une paix durable\" - APNU","og_description":"Alors que la guerre \u00e0 Gaza dure depuis plus de trois mois, le Secr\u00e9taire g\u00e9n\u00e9ral...","og_url":"https:\/\/apnu.be\/index.php\/2024\/01\/26\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\/","og_site_name":"APNU","article_published_time":"2024-01-26T09:58:22+00:00","article_modified_time":"2024-03-28T16:44:56+00:00","og_image":[{"width":1170,"height":530,"url":"https:\/\/apnu.be\/wp-content\/uploads\/2024\/01\/Conseil-de-securite.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/apnu.be\/index.php\/2024\/01\/26\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\/#article","isPartOf":{"@id":"https:\/\/apnu.be\/index.php\/2024\/01\/26\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\/"},"author":{"name":"admin","@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc"},"headline":"Israel-Palestine: \u00ab\u00a0la solution \u00e0 deux \u00e9tats, seul moyen de parvenir \u00e0 une paix durable\u00a0\u00bb","datePublished":"2024-01-26T09:58:22+00:00","dateModified":"2024-03-28T16:44:56+00:00","mainEntityOfPage":{"@id":"https:\/\/apnu.be\/index.php\/2024\/01\/26\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\/"},"wordCount":374,"commentCount":0,"image":{"@id":"https:\/\/apnu.be\/index.php\/2024\/01\/26\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\/#primaryimage"},"thumbnailUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2024\/01\/Conseil-de-securite.jpg","articleSection":["Articles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/apnu.be\/index.php\/2024\/01\/26\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/apnu.be\/index.php\/2024\/01\/26\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\/","url":"https:\/\/apnu.be\/index.php\/2024\/01\/26\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\/","name":"Israel-Palestine: \"la solution \u00e0 deux \u00e9tats, seul moyen de parvenir \u00e0 une paix durable\" - APNU","isPartOf":{"@id":"https:\/\/apnu.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apnu.be\/index.php\/2024\/01\/26\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\/#primaryimage"},"image":{"@id":"https:\/\/apnu.be\/index.php\/2024\/01\/26\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\/#primaryimage"},"thumbnailUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2024\/01\/Conseil-de-securite.jpg","datePublished":"2024-01-26T09:58:22+00:00","dateModified":"2024-03-28T16:44:56+00:00","author":{"@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc"},"breadcrumb":{"@id":"https:\/\/apnu.be\/index.php\/2024\/01\/26\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apnu.be\/index.php\/2024\/01\/26\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/apnu.be\/index.php\/2024\/01\/26\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\/#primaryimage","url":"https:\/\/apnu.be\/wp-content\/uploads\/2024\/01\/Conseil-de-securite.jpg","contentUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2024\/01\/Conseil-de-securite.jpg","width":1170,"height":530},{"@type":"BreadcrumbList","@id":"https:\/\/apnu.be\/index.php\/2024\/01\/26\/israel-palestine-la-solution-a-deux-etats-seul-moyen-de-parvenir-a-une-paix-durable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/apnu.be\/"},{"@type":"ListItem","position":2,"name":"Israel-Palestine: \u00ab\u00a0la solution \u00e0 deux \u00e9tats, seul moyen de parvenir \u00e0 une paix durable\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/apnu.be\/#website","url":"https:\/\/apnu.be\/","name":"APNU","description":"L\u2019Association pour les Nations Unies (A.P.N.U.). Association sans but lucratif (A.S.B.L.)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apnu.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/apnu.be\/index.php\/author\/admin\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/apnu.be\/wp-content\/uploads\/2024\/01\/Conseil-de-securite.jpg","_links":{"self":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/10204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/comments?post=10204"}],"version-history":[{"count":1,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/10204\/revisions"}],"predecessor-version":[{"id":10205,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/10204\/revisions\/10205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/media\/10203"}],"wp:attachment":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/media?parent=10204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/categories?post=10204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/tags?post=10204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}