{"id":10105,"date":"2023-09-13T09:49:33","date_gmt":"2023-09-13T07:49:33","guid":{"rendered":"https:\/\/apnu.be\/?p=10105"},"modified":"2024-09-09T10:45:36","modified_gmt":"2024-09-09T08:45:36","slug":"conference-debat-du-12-octobre-2023","status":"publish","type":"post","link":"https:\/\/apnu.be\/index.php\/2023\/09\/13\/conference-debat-du-12-octobre-2023\/","title":{"rendered":"Conf\u00e9rence-d\u00e9bat du 12 octobre 2023 sur le th\u00e8me: l&rsquo;eau, c&rsquo;est la vie!"},"content":{"rendered":"\n<p>L&rsquo; Association pour les Nations Unies (APNU) a tenu une conf\u00e9rence\/d\u00e9bat sur l&rsquo;eau le <strong>12 octobre 2023<\/strong> en la <strong>salle du Conseil communal d&rsquo;Etterbeek<\/strong> (avenue des casernes 31, Etterbeek). <\/p>\n\n\n\n<p>L&rsquo;eau, c&rsquo;est la vie. Elle est indispensable pour notre sant\u00e9, notre alimentation, pour la biodiversit\u00e9, pour nos besoins \u00e9nerg\u00e9tiques, pour notre industrie, etc. Suite au d\u00e9r\u00e8glement climatique, l&rsquo;acc\u00e8s \u00e0 l&rsquo;eau devient de plus en plus probl\u00e9matique pour des milliards de personnes sur terre dans toutes les r\u00e9gions du monde. Les changements climatiques et les perturbations du cycle hydrologique provoquent davantage de catastrophes comme les s\u00e9cheresses et les inondations. La baisse des nappes phr\u00e9atiques, la fonte des glaciers p\u00e8sent sur les disponibilit\u00e9s en eau douce. Les conflits li\u00e9s \u00e0 l&rsquo;eau se multiplient.<\/p>\n\n\n\n<p>C&rsquo;est pourquoi, pour la premi\u00e8re fois depuis 1977, l\u2019Organisation des Nations Unies a organis\u00e9 du 22 au 24 mars 2023 \u00e0 New York une<strong> conf\u00e9rence sur l&rsquo;eau<\/strong> \u00e0 l&rsquo;issue de laquelle a \u00e9t\u00e9 adopt\u00e9 un \u00ab Programme d&rsquo;action pour l&rsquo;eau \u00bb. L\u2019APNU a tenu \u00e0 d\u00e9velopper les enjeux de cette conf\u00e9rence et \u00e0 mettre en avant les orientations internationales retenues \u00e0 cette occasion et leur cons\u00e9quences pour la Belgique.<\/p>\n\n\n\n<p><strong>Programme<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Colette Njomgang-Fonkeu<\/strong>, Echevine pour la politique sportive et culturelle, Enseignement, Biblioth\u00e8ques \u00e0 la commune d&rsquo;Etterbeek a accueilli les participants.<\/li>\n\n\n\n<li><strong>Nicolas Galudec<\/strong>, Chef adjoint du bureau \u00e0 Bruxelles du Programme des Nations Unies pour l&rsquo;environnement (PNUE), a fait le point sur les r\u00e9sultats de la conf\u00e9rence de l\u2019ONU sur l&rsquo;eau de mars 2023 sur le th\u00e8me: \u00ab Quels enseignements tir\u00e9s et quelles pistes pour l&rsquo;avenir du multilat\u00e9ralisme environnemental ? \u00bb. Sa pr\u00e9sentation est disponible <strong><a href=\"https:\/\/apnu.be\/wp-content\/uploads\/2024\/09\/PPT-CONF-EAU-UNEP-NG-8.pptx\">ici<\/a><\/strong>.<\/li>\n\n\n\n<li><strong>Professeur Marnik Vanclooster<\/strong>, Professeur et chercheur \u00e0 l\u2019UCLouvain, Faculty of Bioscience, Earth and Life Institute, Pr\u00e9sident de la Commission belge du Programme Hydrologique Intergouvernemental (PHI) de l\u2019UNESCO, a expliqu\u00e9 les divers aspects de la probl\u00e9matique de la gestion de l\u2019eau et les implications du PHI pour la Belgique. Vous trouverez sa pr\u00e9sentation <strong><a href=\"https:\/\/apnu.be\/wp-content\/uploads\/2023\/10\/Presentation-Van-Clooster.pptx\">i<\/a><a href=\"https:\/\/apnu.be\/wp-content\/uploads\/2023\/10\/Presentation-Van-Clooster.pdf\">c<\/a><a href=\"https:\/\/apnu.be\/wp-content\/uploads\/2023\/10\/Presentation-Van-Clooster.pptx\">i.<\/a><\/strong><\/li>\n\n\n\n<li><strong>Arnaud De Vanssay<\/strong>, Chef du secteur eau \u00e0 la Direction g\u00e9n\u00e9rale des partenariats internationaux (DG INTPA) de la Commission Europ\u00e9enne, a pr\u00e9sent\u00e9 les actions de l&rsquo;UE dans le cadre du plan d&rsquo;action adopt\u00e9 \u00e0 New York en mars 2023 et de la r\u00e9alisation des objectifs de d\u00e9veloppement durables relatifs \u00e0 l&rsquo;eau. Vous trouverez sa pr\u00e9sentation<a href=\"https:\/\/apnu.be\/wp-content\/uploads\/2023\/10\/APNU-Presentation-A.-de-Vanssay.pdf\"> <strong>ici<\/strong><\/a><strong>.<\/strong><\/li>\n\n\n\n<li><strong>Sophie Colette<\/strong>, expert eau \u00e0 ENABEL, l\u2019Agence belge de d\u00e9veloppement, a parl\u00e9 du r\u00f4le et des actions de la coop\u00e9ration belge dans le secteur de l&rsquo;eau. Vous trouverez sa pr\u00e9sentation <strong><a href=\"https:\/\/apnu.be\/wp-content\/uploads\/2023\/10\/2023-ANUP-presentation-Enabel.pdf\">ici<\/a>.<\/strong><\/li>\n\n\n\n<li>Apr\u00e8s une s\u00e9rie de questions-r\u00e9ponses, <strong>Francoise Tulkens<\/strong>, Pr\u00e9sidente de l&rsquo;APNU,  a tir\u00e9  les conclusions de la conf\u00e9rence.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo; Association pour les Nations Unies (APNU) a tenu une conf\u00e9rence\/d\u00e9bat sur l&rsquo;eau le 12&#8230;<\/p>\n","protected":false},"author":1,"featured_media":10122,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[108],"tags":[],"class_list":["post-10105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conferences"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conf\u00e9rence-d\u00e9bat du 12 octobre 2023 sur le th\u00e8me: l&#039;eau, c&#039;est la vie! - APNU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apnu.be\/index.php\/2023\/09\/13\/conference-debat-du-12-octobre-2023\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conf\u00e9rence-d\u00e9bat du 12 octobre 2023 sur le th\u00e8me: l&#039;eau, c&#039;est la vie! - APNU\" \/>\n<meta property=\"og:description\" content=\"L&rsquo; Association pour les Nations Unies (APNU) a tenu une conf\u00e9rence\/d\u00e9bat sur l&rsquo;eau le 12...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apnu.be\/index.php\/2023\/09\/13\/conference-debat-du-12-octobre-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"APNU\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-13T07:49:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-09T08:45:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apnu.be\/wp-content\/uploads\/2023\/09\/UN-Water-Conference.png\" \/>\n\t<meta property=\"og:image:width\" content=\"982\" \/>\n\t<meta property=\"og:image:height\" content=\"413\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/09\\\/13\\\/conference-debat-du-12-octobre-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/09\\\/13\\\/conference-debat-du-12-octobre-2023\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\"},\"headline\":\"Conf\u00e9rence-d\u00e9bat du 12 octobre 2023 sur le th\u00e8me: l&rsquo;eau, c&rsquo;est la vie!\",\"datePublished\":\"2023-09-13T07:49:33+00:00\",\"dateModified\":\"2024-09-09T08:45:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/09\\\/13\\\/conference-debat-du-12-octobre-2023\\\/\"},\"wordCount\":483,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/09\\\/13\\\/conference-debat-du-12-octobre-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/UN-Water-Conference.png\",\"articleSection\":[\"Conf\u00e9rences\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/09\\\/13\\\/conference-debat-du-12-octobre-2023\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/09\\\/13\\\/conference-debat-du-12-octobre-2023\\\/\",\"url\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/09\\\/13\\\/conference-debat-du-12-octobre-2023\\\/\",\"name\":\"Conf\u00e9rence-d\u00e9bat du 12 octobre 2023 sur le th\u00e8me: l'eau, c'est la vie! - APNU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/09\\\/13\\\/conference-debat-du-12-octobre-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/09\\\/13\\\/conference-debat-du-12-octobre-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/UN-Water-Conference.png\",\"datePublished\":\"2023-09-13T07:49:33+00:00\",\"dateModified\":\"2024-09-09T08:45:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/09\\\/13\\\/conference-debat-du-12-octobre-2023\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/09\\\/13\\\/conference-debat-du-12-octobre-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/09\\\/13\\\/conference-debat-du-12-octobre-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/UN-Water-Conference.png\",\"contentUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/UN-Water-Conference.png\",\"width\":982,\"height\":413},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/09\\\/13\\\/conference-debat-du-12-octobre-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/apnu.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conf\u00e9rence-d\u00e9bat du 12 octobre 2023 sur le th\u00e8me: l&rsquo;eau, c&rsquo;est la vie!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#website\",\"url\":\"https:\\\/\\\/apnu.be\\\/\",\"name\":\"APNU\",\"description\":\"L\u2019Association pour les Nations Unies (A.P.N.U.). Association sans but lucratif (A.S.B.L.)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apnu.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conf\u00e9rence-d\u00e9bat du 12 octobre 2023 sur le th\u00e8me: l'eau, c'est la vie! - APNU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apnu.be\/index.php\/2023\/09\/13\/conference-debat-du-12-octobre-2023\/","og_locale":"fr_FR","og_type":"article","og_title":"Conf\u00e9rence-d\u00e9bat du 12 octobre 2023 sur le th\u00e8me: l'eau, c'est la vie! - APNU","og_description":"L&rsquo; Association pour les Nations Unies (APNU) a tenu une conf\u00e9rence\/d\u00e9bat sur l&rsquo;eau le 12...","og_url":"https:\/\/apnu.be\/index.php\/2023\/09\/13\/conference-debat-du-12-octobre-2023\/","og_site_name":"APNU","article_published_time":"2023-09-13T07:49:33+00:00","article_modified_time":"2024-09-09T08:45:36+00:00","og_image":[{"width":982,"height":413,"url":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/09\/UN-Water-Conference.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/apnu.be\/index.php\/2023\/09\/13\/conference-debat-du-12-octobre-2023\/#article","isPartOf":{"@id":"https:\/\/apnu.be\/index.php\/2023\/09\/13\/conference-debat-du-12-octobre-2023\/"},"author":{"name":"admin","@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc"},"headline":"Conf\u00e9rence-d\u00e9bat du 12 octobre 2023 sur le th\u00e8me: l&rsquo;eau, c&rsquo;est la vie!","datePublished":"2023-09-13T07:49:33+00:00","dateModified":"2024-09-09T08:45:36+00:00","mainEntityOfPage":{"@id":"https:\/\/apnu.be\/index.php\/2023\/09\/13\/conference-debat-du-12-octobre-2023\/"},"wordCount":483,"commentCount":0,"image":{"@id":"https:\/\/apnu.be\/index.php\/2023\/09\/13\/conference-debat-du-12-octobre-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/09\/UN-Water-Conference.png","articleSection":["Conf\u00e9rences"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/apnu.be\/index.php\/2023\/09\/13\/conference-debat-du-12-octobre-2023\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/apnu.be\/index.php\/2023\/09\/13\/conference-debat-du-12-octobre-2023\/","url":"https:\/\/apnu.be\/index.php\/2023\/09\/13\/conference-debat-du-12-octobre-2023\/","name":"Conf\u00e9rence-d\u00e9bat du 12 octobre 2023 sur le th\u00e8me: l'eau, c'est la vie! - APNU","isPartOf":{"@id":"https:\/\/apnu.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apnu.be\/index.php\/2023\/09\/13\/conference-debat-du-12-octobre-2023\/#primaryimage"},"image":{"@id":"https:\/\/apnu.be\/index.php\/2023\/09\/13\/conference-debat-du-12-octobre-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/09\/UN-Water-Conference.png","datePublished":"2023-09-13T07:49:33+00:00","dateModified":"2024-09-09T08:45:36+00:00","author":{"@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc"},"breadcrumb":{"@id":"https:\/\/apnu.be\/index.php\/2023\/09\/13\/conference-debat-du-12-octobre-2023\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apnu.be\/index.php\/2023\/09\/13\/conference-debat-du-12-octobre-2023\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/apnu.be\/index.php\/2023\/09\/13\/conference-debat-du-12-octobre-2023\/#primaryimage","url":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/09\/UN-Water-Conference.png","contentUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/09\/UN-Water-Conference.png","width":982,"height":413},{"@type":"BreadcrumbList","@id":"https:\/\/apnu.be\/index.php\/2023\/09\/13\/conference-debat-du-12-octobre-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/apnu.be\/"},{"@type":"ListItem","position":2,"name":"Conf\u00e9rence-d\u00e9bat du 12 octobre 2023 sur le th\u00e8me: l&rsquo;eau, c&rsquo;est la vie!"}]},{"@type":"WebSite","@id":"https:\/\/apnu.be\/#website","url":"https:\/\/apnu.be\/","name":"APNU","description":"L\u2019Association pour les Nations Unies (A.P.N.U.). Association sans but lucratif (A.S.B.L.)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apnu.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/apnu.be\/index.php\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/09\/UN-Water-Conference.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/10105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/comments?post=10105"}],"version-history":[{"count":12,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/10105\/revisions"}],"predecessor-version":[{"id":10298,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/10105\/revisions\/10298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/media\/10122"}],"wp:attachment":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/media?parent=10105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/categories?post=10105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/tags?post=10105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}