{"id":10064,"date":"2023-06-23T16:37:02","date_gmt":"2023-06-23T14:37:02","guid":{"rendered":"https:\/\/apnu.be\/?p=10064"},"modified":"2025-11-11T10:05:46","modified_gmt":"2025-11-11T09:05:46","slug":"le-29-mai-journee-internationale-des-casques-bleus-de-lonu","status":"publish","type":"post","link":"https:\/\/apnu.be\/index.php\/2023\/06\/23\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\/","title":{"rendered":"Le 29 mai, Journ\u00e9e internationale des Casques bleus de l\u2019ONU"},"content":{"rendered":"\n<p class=\"has-text-align-justify has-black-color has-text-color wp-block-paragraph\">Depuis 1948, 2 millions de soldats de la paix ont servi l\u2019ONU dans le cadre de 71 missions. La journ\u00e9e internationale des Casques bleus des Nations Unies, c\u00e9l\u00e9br\u00e9e le 29 mai, est l\u2019occasion de <a href=\"https:\/\/peacekeeping.un.org\/fr\/our-peacekeepers\" target=\"_blank\" rel=\"noreferrer noopener\">rendre hommage<\/a> aux plus de 4\u2009200 militaires, policiers, fonctionnaires internationaux, volontaires des Nations Unies et personnel national de 43 pays qui ont perdu la vie en servant sous le drapeau des Nations Unies. Cette journ\u00e9e nous invite chaque ann\u00e9e \u00e0 comm\u00e9morer le service des personnes qui \u0153uvrent pour la paix \u00e0 travers le monde dans les op\u00e9rations de maintien de la paix de l\u2019ONU. <\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color wp-block-paragraph\"><a href=\"https:\/\/peacekeeping.un.org\/en\/our-history\" target=\"_blank\" rel=\"noreferrer noopener\">Le maintien de la paix des Nations Unies a commenc\u00e9 en 1948<\/a> lorsque le Conseil de s\u00e9curit\u00e9 a autoris\u00e9 le d\u00e9ploiement d\u2019observateurs militaires au Moyen-Orient. C\u2019est durant la crise de Suez en 1956 que le secr\u00e9taire g\u00e9n\u00e9ral de l\u2019ONU de l\u2019\u00e9poque, Dag Hammarskj\u00f6ld, cr\u00e9a les forces de maintien de la paix de l\u2019ONU, nomm\u00e9es Casques bleus en r\u00e9f\u00e9rence \u00e0 la couleur embl\u00e9matique des Nations Unies et compos\u00e9es de soldats, de policiers et de civils provenant de pays membres de l\u2019ONU, lors de la premi\u00e8re mission de la <a href=\"https:\/\/ask.un.org\/fr\/faq\/237285\" target=\"_blank\" rel=\"noreferrer noopener\">Force d\u2019urgence des Nations Unies (FUNU)<\/a>. Celle-ci consistait \u00e0 superviser la cessation des hostilit\u00e9s, y compris le retrait des forces arm\u00e9es fran\u00e7aises, isra\u00e9liennes et britanniques du territoire \u00e9gyptien et \u00e0 servir d\u2019interm\u00e9diaire entre les forces \u00e9gyptiennes et isra\u00e9liennes apr\u00e8s leur d\u00e9part.<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color wp-block-paragraph\">Le r\u00e9gime juridique des Nations Unies a instaur\u00e9 la r\u00e8gle imp\u00e9rative de l\u2019interdiction du recours \u00e0 la force \u00ab contre l\u2019int\u00e9grit\u00e9 territoriale ou l\u2019ind\u00e9pendance politique de tout Etat \u00bb, \u00e9nonc\u00e9e \u00e0 l\u2019article 2 \u00a74 de la Charte des Nations Unies, comme fondement des relations internationales. Une exception \u00e0 cette r\u00e8gle est toutefois pr\u00e9vue dans le cas o\u00f9, constatant une menace contre la paix et la s\u00e9curit\u00e9 internationales (article 39), le Conseil de s\u00e9curit\u00e9 de l\u2019ONU peut autoriser \u00ab toute action qu\u2019il juge n\u00e9cessaire \u00bb afin d\u2019assurer ou de r\u00e9tablir la paix, y compris le recours \u00e0 la force (article 42) si les mesures non coercitives n\u2019ont pas permis de faire face \u00e0 la menace (article 41). C\u2019est afin d\u2019\u00ab assurer l&rsquo;action rapide et efficace de l&rsquo;Organisation \u00bb que les Etats Membres de l\u2019ONU \u00ab conf\u00e8rent au Conseil de s\u00e9curit\u00e9 la responsabilit\u00e9 principale du maintien de la paix et de la s\u00e9curit\u00e9 internationales \u00bb (article 24 \u00a71). Les mesures militaires requises pour assurer le maintien de la paix sont ainsi prises par les Etats Membres selon l\u2019appr\u00e9ciation du Conseil (article 48 \u00a71) par vote affirmatif de 9 membres, y compris les 5 membres permanents (article 27 \u00a73) qui sont la France, la Russie, le Royaume Uni, les Etats-Unis et la Chine.<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color wp-block-paragraph\">En pratique, l\u2019autorisation du recours \u00e0 la force par le Conseil de s\u00e9curit\u00e9 en vertu du Chapitre VII (action en cas de menace contre la paix, de rupture de la paix et d\u2019acte d\u2019agression) de la Charte des Nations Unies consiste \u00e0 accorder la permission soit \u00e0 des Etats ou soit aux forces des Nations Unies d\u2019user de moyens militaires afin de d\u00e9fendre la s\u00e9curit\u00e9 internationale. Les missions de maintien de la paix de l&rsquo;ONU sont fond\u00e9es sur 3 principes fondamentaux : la neutralit\u00e9 des troupes par rapport au conflit en cours, l\u2019usage minimal de la force qui ne doit \u00eatre utilis\u00e9e qu\u2019en cas de l\u00e9gitime d\u00e9fense ou de n\u00e9cessit\u00e9 de protection du mandat (notamment pour prot\u00e9ger les civils), et la recherche de collaboration avec les gouvernements nationaux et les organisations r\u00e9gionales des pays concern\u00e9s.<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color wp-block-paragraph\">Actuellement, 87 000 soldats, policiers et civils, originaires en majorit\u00e9 de pays du Sud, sont d\u00e9ploy\u00e9s dans 12 op\u00e9rations de maintien de la paix en Afrique, au Moyen-Orient, en Europe et en Asie. Leur mandat comprend des missions multidimensionnelles telles que le contr\u00f4le de cessez-le feu (<a href=\"https:\/\/peacekeeping.un.org\/fr\/mission\/unmogip\" target=\"_blank\" rel=\"noreferrer noopener\">UNMOGIP<\/a>, <a href=\"https:\/\/peacekeeping.un.org\/fr\/mission\/unficyp\" target=\"_blank\" rel=\"noreferrer noopener\">UNFICYP<\/a>, <a href=\"https:\/\/peacekeeping.un.org\/fr\/mission\/fnuod\" target=\"_blank\" rel=\"noreferrer noopener\">FNUOD<\/a>), la protection des civils (<a href=\"https:\/\/peacekeeping.un.org\/fr\/mission\/minusca\" target=\"_blank\" rel=\"noreferrer noopener\">MINUSCA<\/a>, <a href=\"https:\/\/peacekeeping.un.org\/fr\/mission\/monusco\" target=\"_blank\" rel=\"noreferrer noopener\">MONUSCO<\/a>, <a href=\"https:\/\/peacekeeping.un.org\/fr\/mission\/minuss\" target=\"_blank\" rel=\"noreferrer noopener\">MINUSS<\/a>), le d\u00e9sarmement d\u2019ex-combattants (<a href=\"https:\/\/peacekeeping.un.org\/fr\/mission\/fisnua\" target=\"_blank\" rel=\"noreferrer noopener\">FISNUA<\/a>), la d\u00e9fense des droits fondamentaux (<a href=\"https:\/\/peacekeeping.un.org\/fr\/mission\/minuk\" target=\"_blank\" rel=\"noreferrer noopener\">MINUK<\/a>), le soutien aux \u00e9lections libres et justes, le renforcement des capacit\u00e9s des institutions \u00e9tatiques (<a href=\"https:\/\/peacekeeping.un.org\/fr\/mission\/minusma\" target=\"_blank\" rel=\"noreferrer noopener\">MINUSMA<\/a>, <a href=\"https:\/\/peacekeeping.un.org\/fr\/mission\/minurso\" target=\"_blank\" rel=\"noreferrer noopener\">MINURSO<\/a>), et l\u2019aide \u00e0 la reconstruction (<a href=\"https:\/\/peacekeeping.un.org\/fr\/mission\/finul\" target=\"_blank\" rel=\"noreferrer noopener\">FINUL<\/a>) et \u00e0 la r\u00e9conciliation apr\u00e8s conflits (<a href=\"https:\/\/peacekeeping.un.org\/fr\/mission\/onust\" target=\"_blank\" rel=\"noreferrer noopener\">ONUST<\/a>).<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color wp-block-paragraph\">Depuis leur cr\u00e9ation, les Casques bleus ont contribu\u00e9 \u00e0 sauver d\u2019innombrables vies et \u00e0 apporter la s\u00e9curit\u00e9 et la stabilit\u00e9 dans des situations politiques et s\u00e9curitaires des plus fragiles. Mais les op\u00e9rations de maintien de la paix se heurtent aussi \u00e0 des difficult\u00e9s r\u00e9sultant de leurs moyens insuffisants, de la qualit\u00e9 in\u00e9gale de leurs contingents, de leurs mandats parfois inadapt\u00e9s \u00e0 l\u2019environnement dans lequel elles op\u00e8rent (Bosnie-Herz\u00e9govine, Rwanda\u2026), de la mauvaise volont\u00e9 des parties au conflit ou de l\u2019hostilit\u00e9 des populations (RDC).<\/p>\n\n\n\n<p class=\"has-text-align-justify has-black-color has-text-color wp-block-paragraph\">L\u2019\u00e9tablissement d\u2019une paix durable exige des solutions politiques et des partenariats continus entre les Etats membres de l\u2019ONU, les parties au conflit, la soci\u00e9t\u00e9 civile et les organisations non gouvernementales. La poursuite collective de la paix est une condition essentielle pour relever efficacement les d\u00e9fis que posent la reconstruction des pays issus de zones de guerres et l\u2019am\u00e9lioration du niveau de vie des citoyens \u00e0 l\u2019\u00e9chelle mondiale. Le slogan \u00ab<a href=\"https:\/\/peacekeeping.un.org\/fr\/peace-begins-with-me\" target=\"_blank\" rel=\"noreferrer noopener\"> la paix commence avec moi<\/a> \u00bb choisi pour ce 75e anniversaire des missions du maintien de la paix nous invite \u00e0 prendre conscience de notre responsabilit\u00e9 quotidienne dans la construction de la paix internationale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par Edwina Seni, Responsable du Comit\u00e9 r\u00e9daction de l\u2019APNU Jeunes<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La journ\u00e9e internationale des Casques bleus des Nations Unies, c\u00e9l\u00e9br\u00e9e le 29 mai, est l\u2019occasion de rendre hommage aux plus de 4\u2009200 militaires, policiers, fonctionnaires internationaux, volontaires des Nations Unies et personnel national de 43 pays qui ont perdu la vie en servant sous le drapeau des Nations Unies. <\/p>\n","protected":false},"author":1,"featured_media":10065,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[169,118],"tags":[],"class_list":["post-10064","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apnu-jeunes","category-articles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le 29 mai, Journ\u00e9e internationale des Casques bleus de l\u2019ONU - APNU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apnu.be\/index.php\/2023\/06\/23\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le 29 mai, Journ\u00e9e internationale des Casques bleus de l\u2019ONU - APNU\" \/>\n<meta property=\"og:description\" content=\"La journ\u00e9e internationale des Casques bleus des Nations Unies, c\u00e9l\u00e9br\u00e9e le 29 mai, est l\u2019occasion de rendre hommage aux plus de 4\u2009200 militaires, policiers, fonctionnaires internationaux, volontaires des Nations Unies et personnel national de 43 pays qui ont perdu la vie en servant sous le drapeau des Nations Unies.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apnu.be\/index.php\/2023\/06\/23\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\/\" \/>\n<meta property=\"og:site_name\" content=\"APNU\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-23T14:37:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-11T09:05:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apnu.be\/wp-content\/uploads\/2023\/06\/Casques-bleus-e1687530948327.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/06\\\/23\\\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/06\\\/23\\\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\"},\"headline\":\"Le 29 mai, Journ\u00e9e internationale des Casques bleus de l\u2019ONU\",\"datePublished\":\"2023-06-23T14:37:02+00:00\",\"dateModified\":\"2025-11-11T09:05:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/06\\\/23\\\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\\\/\"},\"wordCount\":938,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/06\\\/23\\\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Casques-bleus-e1687530948327.png\",\"articleSection\":[\"APNU Jeunes\",\"Articles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/06\\\/23\\\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/06\\\/23\\\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\\\/\",\"url\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/06\\\/23\\\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\\\/\",\"name\":\"Le 29 mai, Journ\u00e9e internationale des Casques bleus de l\u2019ONU - APNU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/06\\\/23\\\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/06\\\/23\\\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Casques-bleus-e1687530948327.png\",\"datePublished\":\"2023-06-23T14:37:02+00:00\",\"dateModified\":\"2025-11-11T09:05:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/06\\\/23\\\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/06\\\/23\\\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/06\\\/23\\\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Casques-bleus-e1687530948327.png\",\"contentUrl\":\"https:\\\/\\\/apnu.be\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Casques-bleus-e1687530948327.png\",\"width\":1000,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/2023\\\/06\\\/23\\\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/apnu.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le 29 mai, Journ\u00e9e internationale des Casques bleus de l\u2019ONU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#website\",\"url\":\"https:\\\/\\\/apnu.be\\\/\",\"name\":\"APNU\",\"description\":\"L\u2019Association pour les Nations Unies (A.P.N.U.). Association sans but lucratif (A.S.B.L.)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apnu.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/apnu.be\\\/#\\\/schema\\\/person\\\/b1f84938ddb401b1df0d87b68855f7cc\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/apnu.be\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le 29 mai, Journ\u00e9e internationale des Casques bleus de l\u2019ONU - APNU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apnu.be\/index.php\/2023\/06\/23\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\/","og_locale":"fr_FR","og_type":"article","og_title":"Le 29 mai, Journ\u00e9e internationale des Casques bleus de l\u2019ONU - APNU","og_description":"La journ\u00e9e internationale des Casques bleus des Nations Unies, c\u00e9l\u00e9br\u00e9e le 29 mai, est l\u2019occasion de rendre hommage aux plus de 4\u2009200 militaires, policiers, fonctionnaires internationaux, volontaires des Nations Unies et personnel national de 43 pays qui ont perdu la vie en servant sous le drapeau des Nations Unies.","og_url":"https:\/\/apnu.be\/index.php\/2023\/06\/23\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\/","og_site_name":"APNU","article_published_time":"2023-06-23T14:37:02+00:00","article_modified_time":"2025-11-11T09:05:46+00:00","og_image":[{"width":1000,"height":563,"url":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/06\/Casques-bleus-e1687530948327.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/apnu.be\/index.php\/2023\/06\/23\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\/#article","isPartOf":{"@id":"https:\/\/apnu.be\/index.php\/2023\/06\/23\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\/"},"author":{"name":"admin","@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc"},"headline":"Le 29 mai, Journ\u00e9e internationale des Casques bleus de l\u2019ONU","datePublished":"2023-06-23T14:37:02+00:00","dateModified":"2025-11-11T09:05:46+00:00","mainEntityOfPage":{"@id":"https:\/\/apnu.be\/index.php\/2023\/06\/23\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\/"},"wordCount":938,"commentCount":0,"image":{"@id":"https:\/\/apnu.be\/index.php\/2023\/06\/23\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\/#primaryimage"},"thumbnailUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/06\/Casques-bleus-e1687530948327.png","articleSection":["APNU Jeunes","Articles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/apnu.be\/index.php\/2023\/06\/23\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/apnu.be\/index.php\/2023\/06\/23\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\/","url":"https:\/\/apnu.be\/index.php\/2023\/06\/23\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\/","name":"Le 29 mai, Journ\u00e9e internationale des Casques bleus de l\u2019ONU - APNU","isPartOf":{"@id":"https:\/\/apnu.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apnu.be\/index.php\/2023\/06\/23\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\/#primaryimage"},"image":{"@id":"https:\/\/apnu.be\/index.php\/2023\/06\/23\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\/#primaryimage"},"thumbnailUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/06\/Casques-bleus-e1687530948327.png","datePublished":"2023-06-23T14:37:02+00:00","dateModified":"2025-11-11T09:05:46+00:00","author":{"@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc"},"breadcrumb":{"@id":"https:\/\/apnu.be\/index.php\/2023\/06\/23\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apnu.be\/index.php\/2023\/06\/23\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/apnu.be\/index.php\/2023\/06\/23\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\/#primaryimage","url":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/06\/Casques-bleus-e1687530948327.png","contentUrl":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/06\/Casques-bleus-e1687530948327.png","width":1000,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/apnu.be\/index.php\/2023\/06\/23\/le-29-mai-journee-internationale-des-casques-bleus-de-lonu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/apnu.be\/"},{"@type":"ListItem","position":2,"name":"Le 29 mai, Journ\u00e9e internationale des Casques bleus de l\u2019ONU"}]},{"@type":"WebSite","@id":"https:\/\/apnu.be\/#website","url":"https:\/\/apnu.be\/","name":"APNU","description":"L\u2019Association pour les Nations Unies (A.P.N.U.). Association sans but lucratif (A.S.B.L.)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apnu.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/apnu.be\/#\/schema\/person\/b1f84938ddb401b1df0d87b68855f7cc","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e89e9f208d845f01122de42fcf3a35cf929bcb0deb840a867065b8f580c96a66?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/apnu.be\/index.php\/author\/admin\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/apnu.be\/wp-content\/uploads\/2023\/06\/Casques-bleus-e1687530948327.png","_links":{"self":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/10064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/comments?post=10064"}],"version-history":[{"count":3,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/10064\/revisions"}],"predecessor-version":[{"id":10080,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/posts\/10064\/revisions\/10080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/media\/10065"}],"wp:attachment":[{"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/media?parent=10064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/categories?post=10064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apnu.be\/index.php\/wp-json\/wp\/v2\/tags?post=10064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}